{"id":32640,"date":"2026-04-14T06:03:27","date_gmt":"2026-04-14T09:03:27","guid":{"rendered":"https:\/\/miradouronoticias.com\/site\/?p=32640"},"modified":"2026-04-14T06:03:27","modified_gmt":"2026-04-14T09:03:27","slug":"campanha-vai-aplicar-89-mil-doses-de-vacinas-em-territorios-indigenas","status":"publish","type":"post","link":"https:\/\/miradouronoticias.com\/site\/2026\/04\/14\/campanha-vai-aplicar-89-mil-doses-de-vacinas-em-territorios-indigenas\/","title":{"rendered":"Campanha vai aplicar 89 mil doses de vacinas em territ\u00f3rios ind\u00edgenas"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-32641\" src=\"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2026\/04\/pzzb9661-300x179.webp\" alt=\"\" width=\"300\" height=\"179\" srcset=\"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2026\/04\/pzzb9661-300x179.webp 300w, https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2026\/04\/pzzb9661-1024x613.webp 1024w, https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2026\/04\/pzzb9661-768x459.webp 768w, https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2026\/04\/pzzb9661.webp 1170w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><strong>O Minist\u00e9rio da Sa\u00fade espera aplicar mais de\u00a089 mil doses de vacinas em 650 aldeias ind\u00edgenas entre\u00a025 de abril a 25 de maio de 2026. Neste per\u00edodo, ser\u00e1 realizado o\u00a0M\u00eas de Vacina\u00e7\u00e3o dos Povos Ind\u00edgenas (MVPI) para 2026, com o objetivo de ampliar o acesso \u00e0 imuniza\u00e7\u00e3o em territ\u00f3rios ind\u00edgenas, especialmente em \u00e1reas de dif\u00edcil acesso. O an\u00fancio foi feito nesta segunda-feira pela pasta.\u00a0<\/strong><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1685725&amp;o=node\" \/><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1685725&amp;o=node\" \/><\/p>\n<p>No ano passado, foram aplicadas mais de 70 mil doses, alcan\u00e7ando 57 mil ind\u00edgenas. A campanha de 2026 foi anunciada pela secret\u00e1ria de Sa\u00fade Ind\u00edgena, Lucinha Trememb\u00e9, na aldeia Bar\u00e3o do Rio Branco, localizada em M\u00e2ncio Lima (AC). O munic\u00edpio conta tr\u00eas etnias (Puyanawa, Nukini e Nawa), somando cerca de 2 mil ind\u00edgenas.<\/p>\n<p>De acordo com a secret\u00e1ria, iniciar a mobiliza\u00e7\u00e3o em um territ\u00f3rio com desafios hist\u00f3ricos de acesso \u00e9 uma decis\u00e3o estrat\u00e9gica e necess\u00e1ria.<\/p>\n<blockquote><p>\u201cNosso objetivo \u00e9 ampliar a cobertura vacinal justamente em locais de baixa cobertura, garantindo que a informa\u00e7\u00e3o chegue de forma clara e respeitosa, e que a popula\u00e7\u00e3o compreenda a import\u00e2ncia da imuniza\u00e7\u00e3o para a prote\u00e7\u00e3o individual e coletiva\u201d, disse.<\/p><\/blockquote>\n<div class=\"dnd-widget-wrapper context-cheio_8colunas type-image\">\n<div class=\"dnd-atom-rendered\"><img decoding=\"async\" title=\"F\u00e1bio Maciel\/MS\" src=\"https:\/\/imagens.ebc.com.br\/Kp1jRv-dY5A5aACHcMJQ94fgHL8=\/754x0\/smart\/https:\/\/agenciabrasil.ebc.com.br\/sites\/default\/files\/thumbnails\/image\/2026\/04\/13\/img_7490.jpg.jpeg?itok=y1zRlI1l\" alt=\"M\u00e2ncio Lima (AC), 13\/04\/2026 - O Minist\u00e9rio da Sa\u00fade, por meio da Secretaria de Sa\u00fade Ind\u00edgena (SESAI), anunciou o M\u00eas de Vacina\u00e7\u00e3o dos Povos Ind\u00edgenas (MVPI) para 2026. A iniciativa foi anunciada pela secret\u00e1ria Lucinha Trememb\u00e9 nesta manh\u00e3, na aldeia Bar\u00e3o do Rio Branco. A campanha busca ampliar o acesso \u00e0 imuniza\u00e7\u00e3o em territ\u00f3rios ind\u00edgenas, especialmente em \u00e1reas de dif\u00edcil acesso. O MVPI contar\u00e1 com mais de 2,5 mil trabalhadores mobilizados para ampliar a imuniza\u00e7\u00e3o nos 34 DSEI do pa\u00eds. Foto: F\u00e1bio Maciel\/MS\" \/><\/div>\n<div class=\"dnd-caption-wrapper\">\n<div class=\"meta\">O Minist\u00e9rio da Sa\u00fade, anunciou o M\u00eas de Vacina\u00e7\u00e3o dos Povos Ind\u00edgenas (MVPI) para 2026.\u00a0 Foto: F\u00e1bio Maciel\/MS<\/div>\n<\/div>\n<\/div>\n<p>Durante o MVPI, ser\u00e3o ofertados todos os imunobiol\u00f3gicos previstos no Calend\u00e1rio Nacional de Vacina\u00e7\u00e3o: Hepatite A; Hepatite B; BCG; Penta (DTP\/Hib\/Hep B); Pneumoc\u00f3cica 10-valente; Pneumoc\u00f3cica 23-valente (Pneumo 23); VIP (Vacina Inativada Poliomielite); VRH (Vacina Rotav\u00edrus Humano); Meningoc\u00f3cica C (conjugada); Meningoc\u00f3cica ACWY (conjugada); Febre amarela; Tr\u00edplice viral (sarampo, rub\u00e9ola e caxumba); Tetraviral (sarampo, rub\u00e9ola, caxumba e varicela); Varicela (monovalente); DTP (tr\u00edplice bacteriana); dTpa; HPV quadrivalente (papilomav\u00edrus humano); Influenza; e Covid-19.<\/p>\n<p><a href=\"https:\/\/www.whatsapp.com\/channel\/0029VaoRTgrInlqYLSk59B2M\" target=\"_blank\" rel=\"noopener\">&gt;&gt; Siga o canal da\u00a0<strong>Ag\u00eancia Brasil\u00a0<\/strong>no WhatsApp<\/a><\/p>\n<p>A iniciativa \u00e9 realizada desde 2010 e est\u00e1 integrada \u00e0 24\u00aa Semana de Vacina\u00e7\u00e3o nas Am\u00e9ricas e \u00e0 15\u00aa Semana Mundial de Imuniza\u00e7\u00e3o, que iniciam no dia 25 e seguem at\u00e9 2 de maio. Coordenada pela Secretaria de Sa\u00fade Ind\u00edgena (Sesai), a campanha refor\u00e7a a prote\u00e7\u00e3o contra doen\u00e7as imunopreven\u00edveis e contribui para o fortalecimento da aten\u00e7\u00e3o prim\u00e1ria, por meio da busca ativa de ind\u00edgenas ainda n\u00e3o imunizados.<\/p>\n<p>By: miradouronoticias.com.br\/ ag\u00eancia Brasil<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Minist\u00e9rio da Sa\u00fade espera aplicar mais de\u00a089 mil doses de vacinas em 650 aldeias ind\u00edgenas entre\u00a025 de abril a 25 de maio de 2026. Neste per\u00edodo, ser\u00e1 realizado o\u00a0M\u00eas de Vacina\u00e7\u00e3o dos Povos Ind\u00edgenas (MVPI) para 2026, com o objetivo de ampliar o acesso \u00e0 imuniza\u00e7\u00e3o em territ\u00f3rios ind\u00edgenas, especialmente em \u00e1reas de dif\u00edcil [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":32641,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,1,22],"tags":[],"class_list":["post-32640","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","category-destaque-principal","category-saude"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Campanha vai aplicar 89 mil doses de vacinas em territ\u00f3rios ind\u00edgenas - Miradouro Not\u00edcias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/miradouronoticias.com\/site\/2026\/04\/14\/campanha-vai-aplicar-89-mil-doses-de-vacinas-em-territorios-indigenas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Campanha vai aplicar 89 mil doses de vacinas em territ\u00f3rios ind\u00edgenas - Miradouro Not\u00edcias\" \/>\n<meta property=\"og:description\" content=\"O Minist\u00e9rio da Sa\u00fade espera aplicar mais de\u00a089 mil doses de vacinas em 650 aldeias ind\u00edgenas entre\u00a025 de abril a 25 de maio de 2026. Neste per\u00edodo, ser\u00e1 realizado o\u00a0M\u00eas de Vacina\u00e7\u00e3o dos Povos Ind\u00edgenas (MVPI) para 2026, com o objetivo de ampliar o acesso \u00e0 imuniza\u00e7\u00e3o em territ\u00f3rios ind\u00edgenas, especialmente em \u00e1reas de dif\u00edcil [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/miradouronoticias.com\/site\/2026\/04\/14\/campanha-vai-aplicar-89-mil-doses-de-vacinas-em-territorios-indigenas\/\" \/>\n<meta property=\"og:site_name\" content=\"Miradouro Not\u00edcias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-14T09:03:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2026\/04\/pzzb9661.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Cl\u00e1udia Olyver\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cl\u00e1udia Olyver\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2026\\\/04\\\/14\\\/campanha-vai-aplicar-89-mil-doses-de-vacinas-em-territorios-indigenas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2026\\\/04\\\/14\\\/campanha-vai-aplicar-89-mil-doses-de-vacinas-em-territorios-indigenas\\\/\"},\"author\":{\"name\":\"Cl\u00e1udia Olyver\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#\\\/schema\\\/person\\\/73440d8c82222950df86f3e1a16aad3b\"},\"headline\":\"Campanha vai aplicar 89 mil doses de vacinas em territ\u00f3rios ind\u00edgenas\",\"datePublished\":\"2026-04-14T09:03:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2026\\\/04\\\/14\\\/campanha-vai-aplicar-89-mil-doses-de-vacinas-em-territorios-indigenas\\\/\"},\"wordCount\":412,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2026\\\/04\\\/14\\\/campanha-vai-aplicar-89-mil-doses-de-vacinas-em-territorios-indigenas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/pzzb9661.webp\",\"articleSection\":[\"Cultura\",\"Destaque Principal\",\"Sa\u00fade\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2026\\\/04\\\/14\\\/campanha-vai-aplicar-89-mil-doses-de-vacinas-em-territorios-indigenas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2026\\\/04\\\/14\\\/campanha-vai-aplicar-89-mil-doses-de-vacinas-em-territorios-indigenas\\\/\",\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2026\\\/04\\\/14\\\/campanha-vai-aplicar-89-mil-doses-de-vacinas-em-territorios-indigenas\\\/\",\"name\":\"Campanha vai aplicar 89 mil doses de vacinas em territ\u00f3rios ind\u00edgenas - Miradouro Not\u00edcias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2026\\\/04\\\/14\\\/campanha-vai-aplicar-89-mil-doses-de-vacinas-em-territorios-indigenas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2026\\\/04\\\/14\\\/campanha-vai-aplicar-89-mil-doses-de-vacinas-em-territorios-indigenas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/pzzb9661.webp\",\"datePublished\":\"2026-04-14T09:03:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2026\\\/04\\\/14\\\/campanha-vai-aplicar-89-mil-doses-de-vacinas-em-territorios-indigenas\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2026\\\/04\\\/14\\\/campanha-vai-aplicar-89-mil-doses-de-vacinas-em-territorios-indigenas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2026\\\/04\\\/14\\\/campanha-vai-aplicar-89-mil-doses-de-vacinas-em-territorios-indigenas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/pzzb9661.webp\",\"contentUrl\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/pzzb9661.webp\",\"width\":1170,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2026\\\/04\\\/14\\\/campanha-vai-aplicar-89-mil-doses-de-vacinas-em-territorios-indigenas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campanha vai aplicar 89 mil doses de vacinas em territ\u00f3rios ind\u00edgenas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/\",\"name\":\"Miradouro Not\u00edcias\",\"description\":\"Informa\u00e7\u00f5es da cidade e regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#organization\",\"name\":\"Miradouro Not\u00edcias\",\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logomarcamiradouronoticias.png\",\"contentUrl\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logomarcamiradouronoticias.png\",\"width\":747,\"height\":263,\"caption\":\"Miradouro Not\u00edcias\"},\"image\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#\\\/schema\\\/person\\\/73440d8c82222950df86f3e1a16aad3b\",\"name\":\"Cl\u00e1udia Olyver\",\"sameAs\":[\"http:\\\/\\\/www.miradouronoticias.com\"],\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/author\\\/claudia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Campanha vai aplicar 89 mil doses de vacinas em territ\u00f3rios ind\u00edgenas - Miradouro Not\u00edcias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/miradouronoticias.com\/site\/2026\/04\/14\/campanha-vai-aplicar-89-mil-doses-de-vacinas-em-territorios-indigenas\/","og_locale":"pt_BR","og_type":"article","og_title":"Campanha vai aplicar 89 mil doses de vacinas em territ\u00f3rios ind\u00edgenas - Miradouro Not\u00edcias","og_description":"O Minist\u00e9rio da Sa\u00fade espera aplicar mais de\u00a089 mil doses de vacinas em 650 aldeias ind\u00edgenas entre\u00a025 de abril a 25 de maio de 2026. Neste per\u00edodo, ser\u00e1 realizado o\u00a0M\u00eas de Vacina\u00e7\u00e3o dos Povos Ind\u00edgenas (MVPI) para 2026, com o objetivo de ampliar o acesso \u00e0 imuniza\u00e7\u00e3o em territ\u00f3rios ind\u00edgenas, especialmente em \u00e1reas de dif\u00edcil [&hellip;]","og_url":"https:\/\/miradouronoticias.com\/site\/2026\/04\/14\/campanha-vai-aplicar-89-mil-doses-de-vacinas-em-territorios-indigenas\/","og_site_name":"Miradouro Not\u00edcias","article_published_time":"2026-04-14T09:03:27+00:00","og_image":[{"width":1170,"height":700,"url":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2026\/04\/pzzb9661.webp","type":"image\/webp"}],"author":"Cl\u00e1udia Olyver","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Cl\u00e1udia Olyver","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/miradouronoticias.com\/site\/2026\/04\/14\/campanha-vai-aplicar-89-mil-doses-de-vacinas-em-territorios-indigenas\/#article","isPartOf":{"@id":"https:\/\/miradouronoticias.com\/site\/2026\/04\/14\/campanha-vai-aplicar-89-mil-doses-de-vacinas-em-territorios-indigenas\/"},"author":{"name":"Cl\u00e1udia Olyver","@id":"https:\/\/miradouronoticias.com\/site\/#\/schema\/person\/73440d8c82222950df86f3e1a16aad3b"},"headline":"Campanha vai aplicar 89 mil doses de vacinas em territ\u00f3rios ind\u00edgenas","datePublished":"2026-04-14T09:03:27+00:00","mainEntityOfPage":{"@id":"https:\/\/miradouronoticias.com\/site\/2026\/04\/14\/campanha-vai-aplicar-89-mil-doses-de-vacinas-em-territorios-indigenas\/"},"wordCount":412,"commentCount":0,"publisher":{"@id":"https:\/\/miradouronoticias.com\/site\/#organization"},"image":{"@id":"https:\/\/miradouronoticias.com\/site\/2026\/04\/14\/campanha-vai-aplicar-89-mil-doses-de-vacinas-em-territorios-indigenas\/#primaryimage"},"thumbnailUrl":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2026\/04\/pzzb9661.webp","articleSection":["Cultura","Destaque Principal","Sa\u00fade"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/miradouronoticias.com\/site\/2026\/04\/14\/campanha-vai-aplicar-89-mil-doses-de-vacinas-em-territorios-indigenas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/miradouronoticias.com\/site\/2026\/04\/14\/campanha-vai-aplicar-89-mil-doses-de-vacinas-em-territorios-indigenas\/","url":"https:\/\/miradouronoticias.com\/site\/2026\/04\/14\/campanha-vai-aplicar-89-mil-doses-de-vacinas-em-territorios-indigenas\/","name":"Campanha vai aplicar 89 mil doses de vacinas em territ\u00f3rios ind\u00edgenas - Miradouro Not\u00edcias","isPartOf":{"@id":"https:\/\/miradouronoticias.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/miradouronoticias.com\/site\/2026\/04\/14\/campanha-vai-aplicar-89-mil-doses-de-vacinas-em-territorios-indigenas\/#primaryimage"},"image":{"@id":"https:\/\/miradouronoticias.com\/site\/2026\/04\/14\/campanha-vai-aplicar-89-mil-doses-de-vacinas-em-territorios-indigenas\/#primaryimage"},"thumbnailUrl":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2026\/04\/pzzb9661.webp","datePublished":"2026-04-14T09:03:27+00:00","breadcrumb":{"@id":"https:\/\/miradouronoticias.com\/site\/2026\/04\/14\/campanha-vai-aplicar-89-mil-doses-de-vacinas-em-territorios-indigenas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/miradouronoticias.com\/site\/2026\/04\/14\/campanha-vai-aplicar-89-mil-doses-de-vacinas-em-territorios-indigenas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/miradouronoticias.com\/site\/2026\/04\/14\/campanha-vai-aplicar-89-mil-doses-de-vacinas-em-territorios-indigenas\/#primaryimage","url":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2026\/04\/pzzb9661.webp","contentUrl":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2026\/04\/pzzb9661.webp","width":1170,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/miradouronoticias.com\/site\/2026\/04\/14\/campanha-vai-aplicar-89-mil-doses-de-vacinas-em-territorios-indigenas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/miradouronoticias.com\/site\/"},{"@type":"ListItem","position":2,"name":"Campanha vai aplicar 89 mil doses de vacinas em territ\u00f3rios ind\u00edgenas"}]},{"@type":"WebSite","@id":"https:\/\/miradouronoticias.com\/site\/#website","url":"https:\/\/miradouronoticias.com\/site\/","name":"Miradouro Not\u00edcias","description":"Informa\u00e7\u00f5es da cidade e regi\u00e3o","publisher":{"@id":"https:\/\/miradouronoticias.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/miradouronoticias.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/miradouronoticias.com\/site\/#organization","name":"Miradouro Not\u00edcias","url":"https:\/\/miradouronoticias.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/miradouronoticias.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2022\/01\/logomarcamiradouronoticias.png","contentUrl":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2022\/01\/logomarcamiradouronoticias.png","width":747,"height":263,"caption":"Miradouro Not\u00edcias"},"image":{"@id":"https:\/\/miradouronoticias.com\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/miradouronoticias.com\/site\/#\/schema\/person\/73440d8c82222950df86f3e1a16aad3b","name":"Cl\u00e1udia Olyver","sameAs":["http:\/\/www.miradouronoticias.com"],"url":"https:\/\/miradouronoticias.com\/site\/author\/claudia\/"}]}},"_links":{"self":[{"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/posts\/32640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/comments?post=32640"}],"version-history":[{"count":1,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/posts\/32640\/revisions"}],"predecessor-version":[{"id":32642,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/posts\/32640\/revisions\/32642"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/media\/32641"}],"wp:attachment":[{"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/media?parent=32640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/categories?post=32640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/tags?post=32640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}