{"id":31859,"date":"2026-02-04T05:15:01","date_gmt":"2026-02-04T08:15:01","guid":{"rendered":"https:\/\/miradouronoticias.com\/site\/?p=31859"},"modified":"2026-02-04T05:15:01","modified_gmt":"2026-02-04T08:15:01","slug":"senado-aprova-mp-que-cria-programa-gas-do-povo-texto-vai-a-sancao","status":"publish","type":"post","link":"https:\/\/miradouronoticias.com\/site\/2026\/02\/04\/senado-aprova-mp-que-cria-programa-gas-do-povo-texto-vai-a-sancao\/","title":{"rendered":"Senado aprova MP que cria programa G\u00e1s do Povo; texto vai \u00e0 san\u00e7\u00e3o"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-31860\" src=\"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2026\/02\/55077118920_76b0ff4f6c_o-300x179.jpg\" alt=\"\" width=\"300\" height=\"179\" srcset=\"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2026\/02\/55077118920_76b0ff4f6c_o-300x179.jpg 300w, https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2026\/02\/55077118920_76b0ff4f6c_o-1024x613.jpg 1024w, https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2026\/02\/55077118920_76b0ff4f6c_o-768x459.jpg 768w, https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2026\/02\/55077118920_76b0ff4f6c_o.jpg 1170w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>O plen\u00e1rio do Senado Federal aprovou nesta ter\u00e7a-feira (3) a medida provis\u00f3ria (MP) que instituiu o programa G\u00e1s do Povo.\u00a0<strong>O texto assegura gratuidade no botij\u00e3o de g\u00e1s de cozinha (GLP) de 13 quilos (kg) a fam\u00edlias inscritas no Cadastro \u00danico para Programas Sociais do Governo Federal (Cad\u00danico), desde que tenham renda<em>\u00a0per capita\u00a0<\/em>de at\u00e9 meio sal\u00e1rio m\u00ednimo.<\/strong><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1676982&amp;o=node\" \/><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1676982&amp;o=node\" \/><\/p>\n<p>A MP, cuja validade termina em 11 de fevereiro,\u00a0<strong>foi aprovada em menos de 24 horas tanto\u00a0<a href=\"https:\/\/agenciabrasil.ebc.com.br\/politica\/noticia\/2026-02\/camara-aprova-mp-do-programa-gas-do-povo\" target=\"_blank\" rel=\"noopener\">na C\u00e2mara<\/a>\u00a0quanto no Senado, e agora segue para san\u00e7\u00e3o presidencial,<\/strong>\u00a0j\u00e1 que os parlamentares fizeram algumas altera\u00e7\u00f5es no texto.<\/p>\n<p>&#8220;Cabe, aqui, um agradecimento aos plen\u00e1rios da C\u00e2mara dos Deputados e do Senado Federal, por aprovarem, de forma t\u00e3o r\u00e1pida, uma medida que reduz desigualdades e fortalece a coes\u00e3o social. O Congresso Nacional d\u00e1 um recado claro: o bem-estar das pessoas est\u00e1 no centro das nossas decis\u00f5es. Que esse benef\u00edcio chegue r\u00e1pido \u00e0 mesa e \u00e0 vida de quem mais precisa&#8221;, afirmou o presidente do Senado, Davi Alcolumbre (Uni\u00e3o-AP), ao comemorar a aprova\u00e7\u00e3o da medida.<\/p>\n<p>Segundo o Minist\u00e9rio do Desenvolvimento, Assist\u00eancia Social, Fam\u00edlia e Combate \u00e0 Fome (MDS),\u00a0<strong>o G\u00e1s do Povo deve estar em pleno funcionamento em mar\u00e7o, quando pouco mais 15 milh\u00f5es de fam\u00edlias ser\u00e3o beneficiadas<\/strong>. O programa pretende combater a pobreza energ\u00e9tica, definida como a dificuldade de uma fam\u00edlia em ter acesso a servi\u00e7os de energia essenciais e modernos, como ilumina\u00e7\u00e3o, aquecimento, refrigera\u00e7\u00e3o e energia para cozinhar. Atualmente, o programa est\u00e1 instalado em todas as capitais.<\/p>\n<p>O Aux\u00edlio G\u00e1s, benef\u00edcio criado no governo passado e que permite a compra de um botij\u00e3o de 13 kg a cada dois meses por cerca de 4,4 milh\u00f5es de fam\u00edlias de baixa renda, ser\u00e1 substitu\u00eddo. Em seu lugar, o G\u00e1s do Povo consolida a gratuidade do botij\u00e3o em mais de 10 mil revendedoras credenciadas espalhadas pelo pa\u00eds, aumentando o alcance e o n\u00famero de fam\u00edlias atendidas, segundo o governo.<\/p>\n<p>De acordo com o regulamento do programa,<strong>\u00a0a quantidade de recargas gratuitas de 13 kg ser\u00e1 de quatro por ano para fam\u00edlias de duas a tr\u00eas pessoas; para as fam\u00edlias com quatro ou mais pessoas, ser\u00e1 de seis ao ano.<\/strong><\/p>\n<p>O texto tamb\u00e9m cria uma nova modalidade no programa, destinada \u00e0 instala\u00e7\u00e3o de sistemas de baixa emiss\u00e3o de carbono e biodigestores que gerem g\u00e1s metano por decomposi\u00e7\u00e3o de restos de alimentos. Essa modalidade \u00e9 destinada a \u00e1reas rurais e cozinhas comunit\u00e1rias, e ainda depende de regulamento a ser feito pelo governo.<\/p>\n<p><strong>O texto aprovado pela C\u00e2mara e agora confirmado no Senado reformula as prioridades de recebimento do aux\u00edlio<\/strong>. Ter\u00e3o prioridade as fam\u00edlias atingidas por desastres ou em local com situa\u00e7\u00e3o de emerg\u00eancia reconhecida pelo poder p\u00fablico; com mulheres v\u00edtimas de viol\u00eancia dom\u00e9stica sob monitoramento de medidas protetivas de urg\u00eancia; pertencentes a povos e comunidades tradicionais, como ind\u00edgenas e quilombolas; com maior n\u00famero de membros; e com menor renda por pessoa.<\/p>\n<p><em>By: miradouronoticias.com.br\/ *Com informa\u00e7\u00f5es da Ag\u00eancia Senado.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O plen\u00e1rio do Senado Federal aprovou nesta ter\u00e7a-feira (3) a medida provis\u00f3ria (MP) que instituiu o programa G\u00e1s do Povo.\u00a0O texto assegura gratuidade no botij\u00e3o de g\u00e1s de cozinha (GLP) de 13 quilos (kg) a fam\u00edlias inscritas no Cadastro \u00danico para Programas Sociais do Governo Federal (Cad\u00danico), desde que tenham renda\u00a0per capita\u00a0de at\u00e9 meio sal\u00e1rio [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":31860,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,29],"tags":[],"class_list":["post-31859","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque-principal","category-economia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Senado aprova MP que cria programa G\u00e1s do Povo; texto vai \u00e0 san\u00e7\u00e3o - Miradouro Not\u00edcias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/miradouronoticias.com\/site\/2026\/02\/04\/senado-aprova-mp-que-cria-programa-gas-do-povo-texto-vai-a-sancao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Senado aprova MP que cria programa G\u00e1s do Povo; texto vai \u00e0 san\u00e7\u00e3o - Miradouro Not\u00edcias\" \/>\n<meta property=\"og:description\" content=\"O plen\u00e1rio do Senado Federal aprovou nesta ter\u00e7a-feira (3) a medida provis\u00f3ria (MP) que instituiu o programa G\u00e1s do Povo.\u00a0O texto assegura gratuidade no botij\u00e3o de g\u00e1s de cozinha (GLP) de 13 quilos (kg) a fam\u00edlias inscritas no Cadastro \u00danico para Programas Sociais do Governo Federal (Cad\u00danico), desde que tenham renda\u00a0per capita\u00a0de at\u00e9 meio sal\u00e1rio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/miradouronoticias.com\/site\/2026\/02\/04\/senado-aprova-mp-que-cria-programa-gas-do-povo-texto-vai-a-sancao\/\" \/>\n<meta property=\"og:site_name\" content=\"Miradouro Not\u00edcias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-04T08:15:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2026\/02\/55077118920_76b0ff4f6c_o.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cl\u00e1udia Olyver\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cl\u00e1udia Olyver\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2026\\\/02\\\/04\\\/senado-aprova-mp-que-cria-programa-gas-do-povo-texto-vai-a-sancao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2026\\\/02\\\/04\\\/senado-aprova-mp-que-cria-programa-gas-do-povo-texto-vai-a-sancao\\\/\"},\"author\":{\"name\":\"Cl\u00e1udia Olyver\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#\\\/schema\\\/person\\\/73440d8c82222950df86f3e1a16aad3b\"},\"headline\":\"Senado aprova MP que cria programa G\u00e1s do Povo; texto vai \u00e0 san\u00e7\u00e3o\",\"datePublished\":\"2026-02-04T08:15:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2026\\\/02\\\/04\\\/senado-aprova-mp-que-cria-programa-gas-do-povo-texto-vai-a-sancao\\\/\"},\"wordCount\":555,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2026\\\/02\\\/04\\\/senado-aprova-mp-que-cria-programa-gas-do-povo-texto-vai-a-sancao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/55077118920_76b0ff4f6c_o.jpg\",\"articleSection\":[\"Destaque Principal\",\"Economia\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2026\\\/02\\\/04\\\/senado-aprova-mp-que-cria-programa-gas-do-povo-texto-vai-a-sancao\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2026\\\/02\\\/04\\\/senado-aprova-mp-que-cria-programa-gas-do-povo-texto-vai-a-sancao\\\/\",\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2026\\\/02\\\/04\\\/senado-aprova-mp-que-cria-programa-gas-do-povo-texto-vai-a-sancao\\\/\",\"name\":\"Senado aprova MP que cria programa G\u00e1s do Povo; texto vai \u00e0 san\u00e7\u00e3o - Miradouro Not\u00edcias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2026\\\/02\\\/04\\\/senado-aprova-mp-que-cria-programa-gas-do-povo-texto-vai-a-sancao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2026\\\/02\\\/04\\\/senado-aprova-mp-que-cria-programa-gas-do-povo-texto-vai-a-sancao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/55077118920_76b0ff4f6c_o.jpg\",\"datePublished\":\"2026-02-04T08:15:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2026\\\/02\\\/04\\\/senado-aprova-mp-que-cria-programa-gas-do-povo-texto-vai-a-sancao\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2026\\\/02\\\/04\\\/senado-aprova-mp-que-cria-programa-gas-do-povo-texto-vai-a-sancao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2026\\\/02\\\/04\\\/senado-aprova-mp-que-cria-programa-gas-do-povo-texto-vai-a-sancao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/55077118920_76b0ff4f6c_o.jpg\",\"contentUrl\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/55077118920_76b0ff4f6c_o.jpg\",\"width\":1170,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2026\\\/02\\\/04\\\/senado-aprova-mp-que-cria-programa-gas-do-povo-texto-vai-a-sancao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Senado aprova MP que cria programa G\u00e1s do Povo; texto vai \u00e0 san\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/\",\"name\":\"Miradouro Not\u00edcias\",\"description\":\"Informa\u00e7\u00f5es da cidade e regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#organization\",\"name\":\"Miradouro Not\u00edcias\",\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logomarcamiradouronoticias.png\",\"contentUrl\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logomarcamiradouronoticias.png\",\"width\":747,\"height\":263,\"caption\":\"Miradouro Not\u00edcias\"},\"image\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#\\\/schema\\\/person\\\/73440d8c82222950df86f3e1a16aad3b\",\"name\":\"Cl\u00e1udia Olyver\",\"sameAs\":[\"http:\\\/\\\/www.miradouronoticias.com\"],\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/author\\\/claudia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Senado aprova MP que cria programa G\u00e1s do Povo; texto vai \u00e0 san\u00e7\u00e3o - Miradouro Not\u00edcias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/miradouronoticias.com\/site\/2026\/02\/04\/senado-aprova-mp-que-cria-programa-gas-do-povo-texto-vai-a-sancao\/","og_locale":"pt_BR","og_type":"article","og_title":"Senado aprova MP que cria programa G\u00e1s do Povo; texto vai \u00e0 san\u00e7\u00e3o - Miradouro Not\u00edcias","og_description":"O plen\u00e1rio do Senado Federal aprovou nesta ter\u00e7a-feira (3) a medida provis\u00f3ria (MP) que instituiu o programa G\u00e1s do Povo.\u00a0O texto assegura gratuidade no botij\u00e3o de g\u00e1s de cozinha (GLP) de 13 quilos (kg) a fam\u00edlias inscritas no Cadastro \u00danico para Programas Sociais do Governo Federal (Cad\u00danico), desde que tenham renda\u00a0per capita\u00a0de at\u00e9 meio sal\u00e1rio [&hellip;]","og_url":"https:\/\/miradouronoticias.com\/site\/2026\/02\/04\/senado-aprova-mp-que-cria-programa-gas-do-povo-texto-vai-a-sancao\/","og_site_name":"Miradouro Not\u00edcias","article_published_time":"2026-02-04T08:15:01+00:00","og_image":[{"width":1170,"height":700,"url":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2026\/02\/55077118920_76b0ff4f6c_o.jpg","type":"image\/jpeg"}],"author":"Cl\u00e1udia Olyver","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Cl\u00e1udia Olyver","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/miradouronoticias.com\/site\/2026\/02\/04\/senado-aprova-mp-que-cria-programa-gas-do-povo-texto-vai-a-sancao\/#article","isPartOf":{"@id":"https:\/\/miradouronoticias.com\/site\/2026\/02\/04\/senado-aprova-mp-que-cria-programa-gas-do-povo-texto-vai-a-sancao\/"},"author":{"name":"Cl\u00e1udia Olyver","@id":"https:\/\/miradouronoticias.com\/site\/#\/schema\/person\/73440d8c82222950df86f3e1a16aad3b"},"headline":"Senado aprova MP que cria programa G\u00e1s do Povo; texto vai \u00e0 san\u00e7\u00e3o","datePublished":"2026-02-04T08:15:01+00:00","mainEntityOfPage":{"@id":"https:\/\/miradouronoticias.com\/site\/2026\/02\/04\/senado-aprova-mp-que-cria-programa-gas-do-povo-texto-vai-a-sancao\/"},"wordCount":555,"commentCount":0,"publisher":{"@id":"https:\/\/miradouronoticias.com\/site\/#organization"},"image":{"@id":"https:\/\/miradouronoticias.com\/site\/2026\/02\/04\/senado-aprova-mp-que-cria-programa-gas-do-povo-texto-vai-a-sancao\/#primaryimage"},"thumbnailUrl":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2026\/02\/55077118920_76b0ff4f6c_o.jpg","articleSection":["Destaque Principal","Economia"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/miradouronoticias.com\/site\/2026\/02\/04\/senado-aprova-mp-que-cria-programa-gas-do-povo-texto-vai-a-sancao\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/miradouronoticias.com\/site\/2026\/02\/04\/senado-aprova-mp-que-cria-programa-gas-do-povo-texto-vai-a-sancao\/","url":"https:\/\/miradouronoticias.com\/site\/2026\/02\/04\/senado-aprova-mp-que-cria-programa-gas-do-povo-texto-vai-a-sancao\/","name":"Senado aprova MP que cria programa G\u00e1s do Povo; texto vai \u00e0 san\u00e7\u00e3o - Miradouro Not\u00edcias","isPartOf":{"@id":"https:\/\/miradouronoticias.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/miradouronoticias.com\/site\/2026\/02\/04\/senado-aprova-mp-que-cria-programa-gas-do-povo-texto-vai-a-sancao\/#primaryimage"},"image":{"@id":"https:\/\/miradouronoticias.com\/site\/2026\/02\/04\/senado-aprova-mp-que-cria-programa-gas-do-povo-texto-vai-a-sancao\/#primaryimage"},"thumbnailUrl":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2026\/02\/55077118920_76b0ff4f6c_o.jpg","datePublished":"2026-02-04T08:15:01+00:00","breadcrumb":{"@id":"https:\/\/miradouronoticias.com\/site\/2026\/02\/04\/senado-aprova-mp-que-cria-programa-gas-do-povo-texto-vai-a-sancao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/miradouronoticias.com\/site\/2026\/02\/04\/senado-aprova-mp-que-cria-programa-gas-do-povo-texto-vai-a-sancao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/miradouronoticias.com\/site\/2026\/02\/04\/senado-aprova-mp-que-cria-programa-gas-do-povo-texto-vai-a-sancao\/#primaryimage","url":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2026\/02\/55077118920_76b0ff4f6c_o.jpg","contentUrl":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2026\/02\/55077118920_76b0ff4f6c_o.jpg","width":1170,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/miradouronoticias.com\/site\/2026\/02\/04\/senado-aprova-mp-que-cria-programa-gas-do-povo-texto-vai-a-sancao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/miradouronoticias.com\/site\/"},{"@type":"ListItem","position":2,"name":"Senado aprova MP que cria programa G\u00e1s do Povo; texto vai \u00e0 san\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/miradouronoticias.com\/site\/#website","url":"https:\/\/miradouronoticias.com\/site\/","name":"Miradouro Not\u00edcias","description":"Informa\u00e7\u00f5es da cidade e regi\u00e3o","publisher":{"@id":"https:\/\/miradouronoticias.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/miradouronoticias.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/miradouronoticias.com\/site\/#organization","name":"Miradouro Not\u00edcias","url":"https:\/\/miradouronoticias.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/miradouronoticias.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2022\/01\/logomarcamiradouronoticias.png","contentUrl":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2022\/01\/logomarcamiradouronoticias.png","width":747,"height":263,"caption":"Miradouro Not\u00edcias"},"image":{"@id":"https:\/\/miradouronoticias.com\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/miradouronoticias.com\/site\/#\/schema\/person\/73440d8c82222950df86f3e1a16aad3b","name":"Cl\u00e1udia Olyver","sameAs":["http:\/\/www.miradouronoticias.com"],"url":"https:\/\/miradouronoticias.com\/site\/author\/claudia\/"}]}},"_links":{"self":[{"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/posts\/31859","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/comments?post=31859"}],"version-history":[{"count":1,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/posts\/31859\/revisions"}],"predecessor-version":[{"id":31861,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/posts\/31859\/revisions\/31861"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/media\/31860"}],"wp:attachment":[{"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/media?parent=31859"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/categories?post=31859"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/tags?post=31859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}