{"id":31076,"date":"2025-12-16T15:42:38","date_gmt":"2025-12-16T18:42:38","guid":{"rendered":"https:\/\/miradouronoticias.com\/site\/?p=31076"},"modified":"2025-12-16T15:42:38","modified_gmt":"2025-12-16T18:42:38","slug":"segunda-parcela-do-13o-salario-deve-ser-paga-ate-a-proxima-sexta-feira","status":"publish","type":"post","link":"https:\/\/miradouronoticias.com\/site\/2025\/12\/16\/segunda-parcela-do-13o-salario-deve-ser-paga-ate-a-proxima-sexta-feira\/","title":{"rendered":"Segunda parcela do 13\u00ba sal\u00e1rio deve ser paga at\u00e9 a pr\u00f3xima sexta-feira"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-31077\" src=\"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2025\/12\/real_moeda_dinheiro_mcajr_2904223667-300x179.webp\" alt=\"\" width=\"300\" height=\"179\" srcset=\"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2025\/12\/real_moeda_dinheiro_mcajr_2904223667-300x179.webp 300w, https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2025\/12\/real_moeda_dinheiro_mcajr_2904223667-1024x613.webp 1024w, https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2025\/12\/real_moeda_dinheiro_mcajr_2904223667-768x459.webp 768w, https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2025\/12\/real_moeda_dinheiro_mcajr_2904223667.webp 1170w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<header id=\"header-site\" class=\"header-site full-width rel-position\">\n<div class=\"header-veiculo full-width\">\n<aside id=\"nav-menu-mobile\" class=\"nav-menu-mobile\">&nbsp;<\/p>\n<\/aside>\n<\/div>\n<div class=\"header-editorias rowflex full-width\"><\/div>\n<\/header>\n<p><main class=\"main-site\"><\/p>\n<div class=\"region region-content\">\n<div id=\"block-system-main\" class=\"block block-system\">\n<div class=\"content\">\n<div id=\"panel\" class=\"container-noticia rel-position\">\n<div id=\"node-1671953\" class=\"node node-conteudo clearfix\">\n<div class=\"conteudo-noticia\">\n<p><strong>A segunda parcela do d\u00e9cimo terceiro sal\u00e1rio deve ser depositada a 95,3 milh\u00f5es de brasileiros at\u00e9 a pr\u00f3xima sexta-feira (19)<\/strong>. A primeira\u00a0foi paga at\u00e9 28 de novembro, conforme a legisla\u00e7\u00e3o.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1671953&amp;o=node\" \/><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1671953&amp;o=node\" \/><\/p>\n<p><strong>Um dos principais benef\u00edcios trabalhistas do pa\u00eds, o\u00a0sal\u00e1rio extra injetar\u00e1 R$ 369,4 bilh\u00f5es na economia neste ano, segundo c\u00e1lculos do Departamento Intersindical de Estat\u00edstica e Estudos Socioecon\u00f4micos (Dieese)<\/strong>.\u00a0<strong>Em m\u00e9dia, cada trabalhador com carteira assinada dever\u00e1 receber R$ 3.512, somadas as duas parcelas.<\/strong><\/p>\n<p>Essas datas valem apenas para os trabalhadores na ativa. Como nos \u00faltimos anos, o d\u00e9cimo terceiro dos aposentados e pensionistas do Instituto Nacional do Seguro Social (INSS) foi antecipado. A primeira parcela foi paga entre 24 de abril e\u00a08 de maio e a segunda, entre 26 de maio e\u00a06 de junho.<\/p>\n<h2>Quem tem direito<\/h2>\n<p>Segundo a\u00a0<a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/leis\/l4090.htm\" target=\"_blank\" rel=\"noopener\">Lei 4.090\/1962<\/a>, que criou a gratifica\u00e7\u00e3o natalina,\u00a0<strong>t\u00eam direito ao d\u00e9cimo terceiro aposentados, pensionistas e quem trabalhou com carteira assinada por pelo menos 15 dias<\/strong>. Com isso, o m\u00eas em que o empregado tiver trabalhado 15 dias ou mais ser\u00e1 contado como m\u00eas inteiro, com pagamento integral da gratifica\u00e7\u00e3o correspondente \u00e0quele m\u00eas.<\/p>\n<p>Trabalhadores em licen\u00e7a-maternidade e afastados por doen\u00e7a ou por acidente tamb\u00e9m recebem o benef\u00edcio. No caso de demiss\u00e3o sem justa causa, o d\u00e9cimo terceiro deve ser calculado proporcionalmente ao per\u00edodo trabalhado e pago junto com a rescis\u00e3o. No entanto, o trabalhador perde o benef\u00edcio se for dispensado com justa causa.<\/p>\n<h2>C\u00e1lculo proporcional<\/h2>\n<p><strong>O d\u00e9cimo terceiro sal\u00e1rio s\u00f3 ser\u00e1 pago integralmente a quem trabalha h\u00e1 pelo menos um ano na mesma empresa.<\/strong><\/p>\n<p><strong>Quem trabalhou menos tempo receber\u00e1 proporcionalmente.<\/strong>\u00a0A\u00a0cada m\u00eas em que trabalha pelo menos 15 dias, o empregado tem direito a um doze avos (1\/12) do sal\u00e1rio total de dezembro. Dessa forma, o c\u00e1lculo do d\u00e9cimo terceiro considera como um m\u00eas inteiro o prazo de 15 dias trabalhados.<\/p>\n<p>A regra que beneficia o trabalhador o prejudica no caso de excesso de faltas sem justificativa. O m\u00eas inteiro ser\u00e1 descontado do d\u00e9cimo terceiro se o empregado deixar de trabalhar mais de 15 dias no m\u00eas e n\u00e3o justificar a aus\u00eancia.<\/p>\n<h2>Tributa\u00e7\u00e3o<\/h2>\n<p>O trabalhador deve estar atento quanto \u00e0 tributa\u00e7\u00e3o do d\u00e9cimo terceiro. Sobre o d\u00e9cimo terceiro, incide tributa\u00e7\u00e3o de Imposto de Renda, INSS e, no caso do patr\u00e3o, Fundo de Garantia do Tempo de Servi\u00e7o (FGTS).<strong>\u00a0No entanto, os tributos s\u00f3 s\u00e3o cobrados no pagamento da segunda parcela.<\/strong><\/p>\n<p>A primeira metade do sal\u00e1rio \u00e9 paga integralmente, sem descontos. A tributa\u00e7\u00e3o do d\u00e9cimo terceiro \u00e9 informada num campo especial na declara\u00e7\u00e3o anual do Imposto de Renda Pessoa F\u00edsica.<\/p>\n<p>By: miradouronoticias.com.be\/ ag\u00eancia Brasil<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><\/main><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; A segunda parcela do d\u00e9cimo terceiro sal\u00e1rio deve ser depositada a 95,3 milh\u00f5es de brasileiros at\u00e9 a pr\u00f3xima sexta-feira (19). A primeira\u00a0foi paga at\u00e9 28 de novembro, conforme a legisla\u00e7\u00e3o. Um dos principais benef\u00edcios trabalhistas do pa\u00eds, o\u00a0sal\u00e1rio extra injetar\u00e1 R$ 369,4 bilh\u00f5es na economia neste ano, segundo c\u00e1lculos do Departamento Intersindical de Estat\u00edstica [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":31077,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,29],"tags":[],"class_list":["post-31076","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque-principal","category-economia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Segunda parcela do 13\u00ba sal\u00e1rio deve ser paga at\u00e9 a pr\u00f3xima sexta-feira - Miradouro Not\u00edcias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/miradouronoticias.com\/site\/2025\/12\/16\/segunda-parcela-do-13o-salario-deve-ser-paga-ate-a-proxima-sexta-feira\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Segunda parcela do 13\u00ba sal\u00e1rio deve ser paga at\u00e9 a pr\u00f3xima sexta-feira - Miradouro Not\u00edcias\" \/>\n<meta property=\"og:description\" content=\"&nbsp; A segunda parcela do d\u00e9cimo terceiro sal\u00e1rio deve ser depositada a 95,3 milh\u00f5es de brasileiros at\u00e9 a pr\u00f3xima sexta-feira (19). A primeira\u00a0foi paga at\u00e9 28 de novembro, conforme a legisla\u00e7\u00e3o. Um dos principais benef\u00edcios trabalhistas do pa\u00eds, o\u00a0sal\u00e1rio extra injetar\u00e1 R$ 369,4 bilh\u00f5es na economia neste ano, segundo c\u00e1lculos do Departamento Intersindical de Estat\u00edstica [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/miradouronoticias.com\/site\/2025\/12\/16\/segunda-parcela-do-13o-salario-deve-ser-paga-ate-a-proxima-sexta-feira\/\" \/>\n<meta property=\"og:site_name\" content=\"Miradouro Not\u00edcias\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-16T18:42:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2025\/12\/real_moeda_dinheiro_mcajr_2904223667.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Cl\u00e1udia Olyver\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cl\u00e1udia Olyver\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2025\\\/12\\\/16\\\/segunda-parcela-do-13o-salario-deve-ser-paga-ate-a-proxima-sexta-feira\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2025\\\/12\\\/16\\\/segunda-parcela-do-13o-salario-deve-ser-paga-ate-a-proxima-sexta-feira\\\/\"},\"author\":{\"name\":\"Cl\u00e1udia Olyver\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#\\\/schema\\\/person\\\/73440d8c82222950df86f3e1a16aad3b\"},\"headline\":\"Segunda parcela do 13\u00ba sal\u00e1rio deve ser paga at\u00e9 a pr\u00f3xima sexta-feira\",\"datePublished\":\"2025-12-16T18:42:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2025\\\/12\\\/16\\\/segunda-parcela-do-13o-salario-deve-ser-paga-ate-a-proxima-sexta-feira\\\/\"},\"wordCount\":480,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2025\\\/12\\\/16\\\/segunda-parcela-do-13o-salario-deve-ser-paga-ate-a-proxima-sexta-feira\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/real_moeda_dinheiro_mcajr_2904223667.webp\",\"articleSection\":[\"Destaque Principal\",\"Economia\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2025\\\/12\\\/16\\\/segunda-parcela-do-13o-salario-deve-ser-paga-ate-a-proxima-sexta-feira\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2025\\\/12\\\/16\\\/segunda-parcela-do-13o-salario-deve-ser-paga-ate-a-proxima-sexta-feira\\\/\",\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2025\\\/12\\\/16\\\/segunda-parcela-do-13o-salario-deve-ser-paga-ate-a-proxima-sexta-feira\\\/\",\"name\":\"Segunda parcela do 13\u00ba sal\u00e1rio deve ser paga at\u00e9 a pr\u00f3xima sexta-feira - Miradouro Not\u00edcias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2025\\\/12\\\/16\\\/segunda-parcela-do-13o-salario-deve-ser-paga-ate-a-proxima-sexta-feira\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2025\\\/12\\\/16\\\/segunda-parcela-do-13o-salario-deve-ser-paga-ate-a-proxima-sexta-feira\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/real_moeda_dinheiro_mcajr_2904223667.webp\",\"datePublished\":\"2025-12-16T18:42:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2025\\\/12\\\/16\\\/segunda-parcela-do-13o-salario-deve-ser-paga-ate-a-proxima-sexta-feira\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2025\\\/12\\\/16\\\/segunda-parcela-do-13o-salario-deve-ser-paga-ate-a-proxima-sexta-feira\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2025\\\/12\\\/16\\\/segunda-parcela-do-13o-salario-deve-ser-paga-ate-a-proxima-sexta-feira\\\/#primaryimage\",\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/real_moeda_dinheiro_mcajr_2904223667.webp\",\"contentUrl\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/real_moeda_dinheiro_mcajr_2904223667.webp\",\"width\":1170,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2025\\\/12\\\/16\\\/segunda-parcela-do-13o-salario-deve-ser-paga-ate-a-proxima-sexta-feira\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Segunda parcela do 13\u00ba sal\u00e1rio deve ser paga at\u00e9 a pr\u00f3xima sexta-feira\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/\",\"name\":\"Miradouro Not\u00edcias\",\"description\":\"Informa\u00e7\u00f5es da cidade e regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#organization\",\"name\":\"Miradouro Not\u00edcias\",\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logomarcamiradouronoticias.png\",\"contentUrl\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logomarcamiradouronoticias.png\",\"width\":747,\"height\":263,\"caption\":\"Miradouro Not\u00edcias\"},\"image\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#\\\/schema\\\/person\\\/73440d8c82222950df86f3e1a16aad3b\",\"name\":\"Cl\u00e1udia Olyver\",\"sameAs\":[\"http:\\\/\\\/www.miradouronoticias.com\"],\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/author\\\/claudia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Segunda parcela do 13\u00ba sal\u00e1rio deve ser paga at\u00e9 a pr\u00f3xima sexta-feira - Miradouro Not\u00edcias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/miradouronoticias.com\/site\/2025\/12\/16\/segunda-parcela-do-13o-salario-deve-ser-paga-ate-a-proxima-sexta-feira\/","og_locale":"pt_BR","og_type":"article","og_title":"Segunda parcela do 13\u00ba sal\u00e1rio deve ser paga at\u00e9 a pr\u00f3xima sexta-feira - Miradouro Not\u00edcias","og_description":"&nbsp; A segunda parcela do d\u00e9cimo terceiro sal\u00e1rio deve ser depositada a 95,3 milh\u00f5es de brasileiros at\u00e9 a pr\u00f3xima sexta-feira (19). A primeira\u00a0foi paga at\u00e9 28 de novembro, conforme a legisla\u00e7\u00e3o. Um dos principais benef\u00edcios trabalhistas do pa\u00eds, o\u00a0sal\u00e1rio extra injetar\u00e1 R$ 369,4 bilh\u00f5es na economia neste ano, segundo c\u00e1lculos do Departamento Intersindical de Estat\u00edstica [&hellip;]","og_url":"https:\/\/miradouronoticias.com\/site\/2025\/12\/16\/segunda-parcela-do-13o-salario-deve-ser-paga-ate-a-proxima-sexta-feira\/","og_site_name":"Miradouro Not\u00edcias","article_published_time":"2025-12-16T18:42:38+00:00","og_image":[{"width":1170,"height":700,"url":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2025\/12\/real_moeda_dinheiro_mcajr_2904223667.webp","type":"image\/webp"}],"author":"Cl\u00e1udia Olyver","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Cl\u00e1udia Olyver","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/miradouronoticias.com\/site\/2025\/12\/16\/segunda-parcela-do-13o-salario-deve-ser-paga-ate-a-proxima-sexta-feira\/#article","isPartOf":{"@id":"https:\/\/miradouronoticias.com\/site\/2025\/12\/16\/segunda-parcela-do-13o-salario-deve-ser-paga-ate-a-proxima-sexta-feira\/"},"author":{"name":"Cl\u00e1udia Olyver","@id":"https:\/\/miradouronoticias.com\/site\/#\/schema\/person\/73440d8c82222950df86f3e1a16aad3b"},"headline":"Segunda parcela do 13\u00ba sal\u00e1rio deve ser paga at\u00e9 a pr\u00f3xima sexta-feira","datePublished":"2025-12-16T18:42:38+00:00","mainEntityOfPage":{"@id":"https:\/\/miradouronoticias.com\/site\/2025\/12\/16\/segunda-parcela-do-13o-salario-deve-ser-paga-ate-a-proxima-sexta-feira\/"},"wordCount":480,"commentCount":0,"publisher":{"@id":"https:\/\/miradouronoticias.com\/site\/#organization"},"image":{"@id":"https:\/\/miradouronoticias.com\/site\/2025\/12\/16\/segunda-parcela-do-13o-salario-deve-ser-paga-ate-a-proxima-sexta-feira\/#primaryimage"},"thumbnailUrl":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2025\/12\/real_moeda_dinheiro_mcajr_2904223667.webp","articleSection":["Destaque Principal","Economia"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/miradouronoticias.com\/site\/2025\/12\/16\/segunda-parcela-do-13o-salario-deve-ser-paga-ate-a-proxima-sexta-feira\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/miradouronoticias.com\/site\/2025\/12\/16\/segunda-parcela-do-13o-salario-deve-ser-paga-ate-a-proxima-sexta-feira\/","url":"https:\/\/miradouronoticias.com\/site\/2025\/12\/16\/segunda-parcela-do-13o-salario-deve-ser-paga-ate-a-proxima-sexta-feira\/","name":"Segunda parcela do 13\u00ba sal\u00e1rio deve ser paga at\u00e9 a pr\u00f3xima sexta-feira - Miradouro Not\u00edcias","isPartOf":{"@id":"https:\/\/miradouronoticias.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/miradouronoticias.com\/site\/2025\/12\/16\/segunda-parcela-do-13o-salario-deve-ser-paga-ate-a-proxima-sexta-feira\/#primaryimage"},"image":{"@id":"https:\/\/miradouronoticias.com\/site\/2025\/12\/16\/segunda-parcela-do-13o-salario-deve-ser-paga-ate-a-proxima-sexta-feira\/#primaryimage"},"thumbnailUrl":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2025\/12\/real_moeda_dinheiro_mcajr_2904223667.webp","datePublished":"2025-12-16T18:42:38+00:00","breadcrumb":{"@id":"https:\/\/miradouronoticias.com\/site\/2025\/12\/16\/segunda-parcela-do-13o-salario-deve-ser-paga-ate-a-proxima-sexta-feira\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/miradouronoticias.com\/site\/2025\/12\/16\/segunda-parcela-do-13o-salario-deve-ser-paga-ate-a-proxima-sexta-feira\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/miradouronoticias.com\/site\/2025\/12\/16\/segunda-parcela-do-13o-salario-deve-ser-paga-ate-a-proxima-sexta-feira\/#primaryimage","url":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2025\/12\/real_moeda_dinheiro_mcajr_2904223667.webp","contentUrl":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2025\/12\/real_moeda_dinheiro_mcajr_2904223667.webp","width":1170,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/miradouronoticias.com\/site\/2025\/12\/16\/segunda-parcela-do-13o-salario-deve-ser-paga-ate-a-proxima-sexta-feira\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/miradouronoticias.com\/site\/"},{"@type":"ListItem","position":2,"name":"Segunda parcela do 13\u00ba sal\u00e1rio deve ser paga at\u00e9 a pr\u00f3xima sexta-feira"}]},{"@type":"WebSite","@id":"https:\/\/miradouronoticias.com\/site\/#website","url":"https:\/\/miradouronoticias.com\/site\/","name":"Miradouro Not\u00edcias","description":"Informa\u00e7\u00f5es da cidade e regi\u00e3o","publisher":{"@id":"https:\/\/miradouronoticias.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/miradouronoticias.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/miradouronoticias.com\/site\/#organization","name":"Miradouro Not\u00edcias","url":"https:\/\/miradouronoticias.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/miradouronoticias.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2022\/01\/logomarcamiradouronoticias.png","contentUrl":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2022\/01\/logomarcamiradouronoticias.png","width":747,"height":263,"caption":"Miradouro Not\u00edcias"},"image":{"@id":"https:\/\/miradouronoticias.com\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/miradouronoticias.com\/site\/#\/schema\/person\/73440d8c82222950df86f3e1a16aad3b","name":"Cl\u00e1udia Olyver","sameAs":["http:\/\/www.miradouronoticias.com"],"url":"https:\/\/miradouronoticias.com\/site\/author\/claudia\/"}]}},"_links":{"self":[{"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/posts\/31076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/comments?post=31076"}],"version-history":[{"count":1,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/posts\/31076\/revisions"}],"predecessor-version":[{"id":31078,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/posts\/31076\/revisions\/31078"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/media\/31077"}],"wp:attachment":[{"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/media?parent=31076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/categories?post=31076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/tags?post=31076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}