{"id":25857,"date":"2024-09-28T07:56:41","date_gmt":"2024-09-28T10:56:41","guid":{"rendered":"https:\/\/miradouronoticias.com\/site\/?p=25857"},"modified":"2024-09-28T07:56:41","modified_gmt":"2024-09-28T10:56:41","slug":"doacao-de-orgaos-conheca-exigencias-e-tire-duvidas-sobre-transplantes","status":"publish","type":"post","link":"https:\/\/miradouronoticias.com\/site\/2024\/09\/28\/doacao-de-orgaos-conheca-exigencias-e-tire-duvidas-sobre-transplantes\/","title":{"rendered":"Doa\u00e7\u00e3o de \u00f3rg\u00e3os: conhe\u00e7a exig\u00eancias e tire d\u00favidas sobre transplantes"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-25858\" src=\"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2024\/09\/5190610858_3e7437a7e6_c_0-300x179.webp\" alt=\"\" width=\"300\" height=\"179\" srcset=\"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2024\/09\/5190610858_3e7437a7e6_c_0-300x179.webp 300w, https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2024\/09\/5190610858_3e7437a7e6_c_0-1024x613.webp 1024w, https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2024\/09\/5190610858_3e7437a7e6_c_0-768x459.webp 768w, https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2024\/09\/5190610858_3e7437a7e6_c_0.webp 1170w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<header id=\"header-site\" class=\"header-site full-width rel-position\">\n<div class=\"header-veiculo full-width\">\n<aside id=\"nav-menu-mobile\" class=\"nav-menu-mobile\">\n<div class=\"search-container full-width\" style=\"text-align: center;\"><input id=\"pesquisa-ebc\" class=\"search-bar\" type=\"text\" placeholder=\"Digite o termo da busca\" \/><button id=\"search-button\" class=\"search-button\" aria-label=\"Buscar\"><\/button><span style=\"color: #000000; font-family: Arial;\"><span style=\"font-size: 13.3333px; background-color: #efefef;\">A <\/span><\/span>cada 14 pessoas que manifestam interesse em doar \u00f3rg\u00e3os no Brasil, apenas quatro efetuam a doa\u00e7\u00e3o. De acordo com o Minist\u00e9rio da Sa\u00fade, um dos principais obst\u00e1culos \u00e9 a recusa familiar. Por esse motivo, no Dia Nacional da Doa\u00e7\u00e3o de \u00d3rg\u00e3os, lembrado nesta sexta-feira (27), a pasta encabe\u00e7a uma campanha com o tema <em>Doa\u00e7\u00e3o de \u00f3rg\u00e3os: precisamos falar sim<\/em>. A proposta \u00e9 alertar para a necessidade de di\u00e1logo e da desmistifica\u00e7\u00e3o do ato de doar \u00f3rg\u00e3os.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1613810&amp;o=node\" \/><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1613810&amp;o=node\" \/><\/div>\n<\/aside>\n<\/div>\n<\/header>\n<p><main class=\"main-site\"><\/p>\n<div class=\"region region-content\">\n<div id=\"block-system-main\" class=\"block block-system\">\n<div class=\"content\">\n<div id=\"panel\" class=\"container-noticia rel-position\">\n<div id=\"node-1613810\" class=\"node node-conteudo clearfix\">\n<div class=\"conteudo-noticia\">\n<p>Dentre os motivos citados para n\u00e3o autorizar a doa\u00e7\u00e3o de \u00f3rg\u00e3os, segundo o minist\u00e9rio, est\u00e3o a n\u00e3o aceita\u00e7\u00e3o da manipula\u00e7\u00e3o do corpo; cren\u00e7a religiosa; medo da rea\u00e7\u00e3o de parentes e familiares; desconfian\u00e7a da assist\u00eancia m\u00e9dica; e a n\u00e3o compreens\u00e3o do diagn\u00f3stico de morte encef\u00e1lica, que leva \u00e0 ideia que, de alguma forma, seria poss\u00edvel reverter o quadro.<\/p>\n<p>\u201cPor isso, falar sobre o assunto \u00e9 o primeiro passo para se tornar um doador\u201d, destaca a pasta.<\/p>\n<p>Ao longo do primeiro semestre deste ano, 14.352 transplantes foram realizados via Sistema \u00danico de Sa\u00fade (SUS). O n\u00famero \u00e9 maior que o registrado no mesmo per\u00edodo de 2023, quando foram contabilizados 13,9 mil procedimentos. Os \u00f3rg\u00e3os mais doados foram rins, f\u00edgado, cora\u00e7\u00e3o, p\u00e2ncreas e pulm\u00e3o, al\u00e9m de c\u00f3rnea e medula \u00f3ssea, que s\u00e3o, tecnicamente, tecidos. Ainda assim, mais de 43 mil brasileiros comp\u00f5em a lista de espera por um transplante.<\/p>\n<h2>&gt;&gt; Confira, a seguir, as principais perguntas e respostas envolvendo o processo de doa\u00e7\u00e3o de \u00f3rg\u00e3os (com base em\u00a0informa\u00e7\u00f5es do Minist\u00e9rio da Sa\u00fade:<\/h2>\n<h2>O que \u00e9 a doa\u00e7\u00e3o de \u00f3rg\u00e3os?<\/h2>\n<p>\u00c9 o ato por meio do qual podem ser doadas partes do corpo, sejam \u00f3rg\u00e3os ou tecidos, para serem utilizados no tratamento de outra pessoa com a finalidade de reestabelecer a fun\u00e7\u00e3o de um \u00f3rg\u00e3o ou tecido doente.<\/p>\n<p>De um \u00fanico doador, \u00e9 poss\u00edvel obter diversos \u00f3rg\u00e3os e tecidos, incluindo rins, f\u00edgado, cora\u00e7\u00e3o, pulm\u00f5es, p\u00e2ncreas, intestino, c\u00f3rneas, valvas card\u00edacas, pele, ossos e tend\u00f5es.<\/p>\n<p>A doa\u00e7\u00e3o de \u00f3rg\u00e3os como rim, parte do f\u00edgado, parte do pulm\u00e3o e medula \u00f3ssea pode ser feita em vida. J\u00e1 a doa\u00e7\u00e3o de \u00f3rg\u00e3os de pessoas falecidas somente ocorre\u00a0ap\u00f3s a confirma\u00e7\u00e3o do diagn\u00f3stico de morte encef\u00e1lica ou de uma parada cardiorrespirat\u00f3ria.<\/p>\n<p>Na morte encef\u00e1lica, pacientes sofreram um acidente que provocou traumatismo craniano, como acidente com carro, moto e quedas, ou sofreram um acidente vascular cerebral (AVC).<\/p>\n<h2>Por que doar \u00f3rg\u00e3os?<\/h2>\n<p>Doar \u00f3rg\u00e3os pode salvar vidas em casos de \u00f3rg\u00e3os vitais, como o cora\u00e7\u00e3o, al\u00e9m de devolver qualidade de vida nos casos em que o \u00f3rg\u00e3o transplantado n\u00e3o \u00e9 vital, como acontece com os rins.<\/p>\n<p>A doa\u00e7\u00e3o de \u00f3rg\u00e3os prolonga a expectativa de vida de pessoas que precisam de um transplante, permitindo o restabelecimento da sa\u00fade e, muitas vezes, at\u00e9 mesmo a retomada de atividades cotidianas.<\/p>\n<h2>O que preciso fazer para ser um doador?<\/h2>\n<p>Se voc\u00ea deseja ser um doador de \u00f3rg\u00e3os, avisar aos parentes\u00a0\u00e9 o mais importante, j\u00e1 que a lei brasileira exige o consentimento da fam\u00edlia para a retirada de \u00f3rg\u00e3os e tecidos para transplante.<\/p>\n<p>N\u00e3o \u00e9 necess\u00e1rio deixar a vontade expressa em documentos ou cart\u00f3rios \u2013 basta que sua fam\u00edlia atenda ao seu pedido e autorize a doa\u00e7\u00e3o.<\/p>\n<blockquote><p>Por isso, comunicar \u00e0 fam\u00edlia que voc\u00ea \u00e9 um doador de \u00f3rg\u00e3os facilita o processo de transplantes. E se voc\u00ea tem um parente doador, respeite a vontade dele.<\/p><\/blockquote>\n<h2>O que \u00e9 um doador de \u00f3rg\u00e3os vivo e o que ele pode doar?<\/h2>\n<p>Um doador vivo \u00e9 qualquer pessoa juridicamente capaz, atendidos os preceitos legais quanto \u00e0 chamada doa\u00e7\u00e3o intervivos, que esteja em condi\u00e7\u00f5es satisfat\u00f3rias de sa\u00fade e que concorde com a doa\u00e7\u00e3o, desde que n\u00e3o prejudique sua pr\u00f3pria sa\u00fade.<\/p>\n<p>O doador vivo pode doar um dos rins, parte do f\u00edgado, parte do pulm\u00e3o ou parte da medula \u00f3ssea. A compatibilidade sangu\u00ednea \u00e9 primordial em todos os casos.<\/p>\n<p>Pela lei, parentes at\u00e9 o quarto grau e c\u00f4njuges podem ser doadores em vida. N\u00e3o parentes, somente com autoriza\u00e7\u00e3o judicial.<\/p>\n<p>Nesse contexto, o doador est\u00e1 sujeito a riscos normais de se submeter a uma cirurgia com anestesia geral. Antes do procedimento, entretanto, s\u00e3o feitos exames a fim de minimizar os riscos.<\/p>\n<h2>O que \u00e9 um doador de \u00f3rg\u00e3os falecido e o que ele pode doar?<\/h2>\n<p>Existem dois tipos de doadores falecidos:<\/p>\n<p><strong>&#8211; doador falecido ap\u00f3s morte encef\u00e1lica:<\/strong>\u00a0paciente cuja morte encef\u00e1lica foi constatada segundo crit\u00e9rios definidos pela legisla\u00e7\u00e3o do pa\u00eds e que n\u00e3o tenha sofrido parada cardiorrespirat\u00f3ria.<\/p>\n<p>O doador falecido, nessa condi\u00e7\u00e3o, pode doar cora\u00e7\u00e3o, pulm\u00f5es, f\u00edgado, p\u00e2ncreas, intestino, rins, c\u00f3rnea, vasos, pele, ossos e tend\u00f5es. A retirada dos \u00f3rg\u00e3os \u00e9 realizada em centro cir\u00fargico. Para que o procedimento aconte\u00e7a, \u00e9 necess\u00e1ria a manuten\u00e7\u00e3o da circula\u00e7\u00e3o sangu\u00ednea do paciente at\u00e9 o momento da retirada do \u00f3rg\u00e3o a ser doado.<\/p>\n<p><strong>&#8211; doador por parada cardiorrespirat\u00f3ria:\u00a0<\/strong>paciente cuja morte foi constatada por crit\u00e9rios cardiorrespirat\u00f3rios (cora\u00e7\u00e3o parado). O doador falecido, nessa condi\u00e7\u00e3o, pode doar apenas tecidos para transplante, incluindo c\u00f3rnea, vasos, pele, ossos e tend\u00f5es.<\/p>\n<p>Em ambos os casos, a doa\u00e7\u00e3o s\u00f3 acontece mediante autoriza\u00e7\u00e3o da fam\u00edlia.<\/p>\n<h2>Quem n\u00e3o pode ser um doador de \u00f3rg\u00e3os?<\/h2>\n<p>N\u00e3o existe restri\u00e7\u00e3o absoluta para a doa\u00e7\u00e3o de \u00f3rg\u00e3os. Entretanto, o ato pressup\u00f5e alguns crit\u00e9rios m\u00ednimos como o conhecimento da causa da morte e a aus\u00eancia de doen\u00e7as infecciosas ativas, dentre outros.<\/p>\n<p>Tamb\u00e9m n\u00e3o poder\u00e3o ser doadoras pessoas que n\u00e3o possuem documenta\u00e7\u00e3o ou menores de 18 anos sem a autoriza\u00e7\u00e3o dos respons\u00e1veis.<\/p>\n<h2>Por que existem poucos doadores de \u00f3rg\u00e3os?<\/h2>\n<p>A negativa familiar \u00e9 um dos principais motivos para que um \u00f3rg\u00e3o n\u00e3o seja doado no Brasil.<\/p>\n<blockquote><p>Atualmente, aproximadamente metade das fam\u00edlias entrevistadas n\u00e3o concorda que sejam retirados \u00f3rg\u00e3os e tecidos do ente falecido para doa\u00e7\u00e3o.<\/p><\/blockquote>\n<p>Em muitos desses casos, a pessoa poderia ter sido um doador. Da\u00ed a necessidade de conversar previamente com sua fam\u00edlia sobre o desejo de doar \u00f3rg\u00e3os.<\/p>\n<h2>Existe limite de idade para doar \u00f3rg\u00e3os?<\/h2>\n<p>O que determina se um \u00f3rg\u00e3o \u00e9 vi\u00e1vel ou n\u00e3o para transplante \u00e9 o estado de sa\u00fade do doador. No entanto, algumas condi\u00e7\u00f5es podem restringir limites de idade em situa\u00e7\u00f5es espec\u00edficas.<\/p>\n<h2>Para quem v\u00e3o os \u00f3rg\u00e3os doados?<\/h2>\n<p>Para pacientes que necessitam de um transplante e j\u00e1 est\u00e3o aguardando em uma lista de espera unificada e informatizada.<\/p>\n<p>A posi\u00e7\u00e3o nessa lista de espera \u00e9 definida por crit\u00e9rios t\u00e9cnicos como tempo de espera, urg\u00eancia do procedimento e compatibilidade sangu\u00ednea entre doador e receptor.<\/p>\n<p>A compatibilidade gen\u00e9tica entre doador e receptores, quando necess\u00e1ria, \u00e9 determinada por exames laboratoriais. Para alguns tipos de transplantes \u00e9 exigida ainda a compatibilidade antropom\u00e9trica (combina\u00e7\u00e3o de medidas como peso, altura e circunfer\u00eancias).<\/p>\n<p>Cabe \u00e0 central estadual de transplantes, por meio do sistema informatizado, gerar a lista de receptores compat\u00edveis com o doador em quest\u00e3o.<\/p>\n<p>Se n\u00e3o existirem receptores compat\u00edveis no estado ou se a unidade federativa em quest\u00e3o n\u00e3o realizar a modalidade de transplante referente ao \u00f3rg\u00e3o doado, ele \u00e9 ofertado \u00e0 Central Nacional de Transplantes para distribui\u00e7\u00e3o nacional.<\/p>\n<h2>O que \u00e9 o Sistema de Lista \u00danica?<\/h2>\n<p>O Sistema de Lista \u00danica \u00e9 constitu\u00eddo pelo conjunto de potenciais receptores brasileiros, natos, naturalizados ou estrangeiros residentes no pa\u00eds, inscritos para o recebimento de cada tipo de \u00f3rg\u00e3o, tecido ou c\u00e9lula.<\/p>\n<p>Esse sistema \u00e9 regulado por um conjunto de crit\u00e9rios espec\u00edficos para a distribui\u00e7\u00e3o a potenciais receptores que constitui o Cadastro T\u00e9cnico \u00danico (CTU).<\/p>\n<p>A lista \u00e9 \u00fanica, organizada por estado ou regi\u00e3o, e monitorada pelo Sistema Nacional de Transplantes (SNT) e por \u00f3rg\u00e3os de controle federais, o que impossibilita que uma pessoa conste em mais de uma lista, al\u00e9m de permitir que a ordem legal seja obedecida.<\/p>\n<h2>Como se identifica um poss\u00edvel doador?<\/h2>\n<p>As Organiza\u00e7\u00f5es de Procura de \u00d3rg\u00e3os (OPO) atuam em parceria com as Comiss\u00f5es Intra-hospitalares de Doa\u00e7\u00e3o de \u00d3rg\u00e3os e Tecidos para Transplante, junto a hospitais com perfil notificante de uma determinada regi\u00e3o geogr\u00e1fica, identificando potenciais doadores e viabilizando o processo de doa\u00e7\u00e3o.<\/p>\n<h2>O que acontece depois de autorizada a doa\u00e7\u00e3o?<\/h2>\n<p>Se existe um doador em potencial, com morte encef\u00e1lica confirmada e mediante autoriza\u00e7\u00e3o da fam\u00edlia para que ocorra a retirada dos \u00f3rg\u00e3os, s\u00e3o mantidos os recursos para a preserva\u00e7\u00e3o das fun\u00e7\u00f5es vitais dos \u00f3rg\u00e3os.<\/p>\n<p>As a\u00e7\u00f5es seguem a seguinte sequ\u00eancia:<\/p>\n<p>&#8211; o hospital notifica a central estadual de transplantes sobre um paciente em morte encef\u00e1lica (potencial doador de \u00f3rg\u00e3os e tecidos) ou com parada cardiorrespirat\u00f3ria (potencial doador de tecidos);<\/p>\n<p>&#8211; a central de transplantes aguarda a confirma\u00e7\u00e3o do diagn\u00f3stico de morte encef\u00e1lica e inicia os testes de compatibilidade entre o potencial doador e potenciais receptores em lista de espera. Quando existe mais de um receptor compat\u00edvel, a decis\u00e3o de quem vai receber o \u00f3rg\u00e3o passa por crit\u00e9rios como tempo de espera e urg\u00eancia do procedimento;<\/p>\n<p>&#8211; a central de transplantes, por meio de um sistema informatizado, gera uma lista de potenciais receptores para cada \u00f3rg\u00e3o e comunica aos hospitais onde eles s\u00e3o atendidos;<\/p>\n<p>&#8211; as equipes de transplante, junto \u00e0 central de transplante, adotam as medidas necess\u00e1rias para viabilizar a retirada dos \u00f3rg\u00e3os (meio de transporte, cirurgi\u00f5es e pessoal de apoio, por exemplo);<\/p>\n<p>&#8211; os \u00f3rg\u00e3os s\u00e3o retirados e o transplante \u00e9 realizado;<\/p>\n<p>J\u00e1 nos casos de morte por parada cardiorrespirat\u00f3ria, ap\u00f3s avalia\u00e7\u00e3o do doador por crit\u00e9rios estabelecidos, tamb\u00e9m mediante autoriza\u00e7\u00e3o da fam\u00edlia, os tecidos s\u00e3o retirados e encaminhados para bancos de tecidos.<\/p>\n<h2>Quem retira os \u00f3rg\u00e3os de um doador?<\/h2>\n<p>Ap\u00f3s a confirma\u00e7\u00e3o de morte encef\u00e1lica, a autoriza\u00e7\u00e3o da fam\u00edlia e a localiza\u00e7\u00e3o de um receptor compat\u00edvel, a retirada dos \u00f3rg\u00e3os para transplante \u00e9 realizada em um centro cir\u00fargico, por uma equipe de cirurgi\u00f5es autorizada pelo Minist\u00e9rio da Sa\u00fade e com treinamento espec\u00edfico para esse tipo de procedimento.<\/p>\n<p>Em seguida, o corpo \u00e9 devidamente reconstitu\u00eddo e liberado para os familiares.<\/p>\n<h2>Ap\u00f3s a doa\u00e7\u00e3o, o corpo do doador fica deformado?<\/h2>\n<p>N\u00e3o. Ap\u00f3s a retirada dos \u00f3rg\u00e3os e tecidos, a equipe m\u00e9dica recomp\u00f5e o corpo do doador, sendo vis\u00edveis apenas os pontos do local operado, n\u00e3o impedindo a realiza\u00e7\u00e3o do vel\u00f3rio.<\/p>\n<p>Para a doa\u00e7\u00e3o de tecidos oculares, o profissional coloca uma pr\u00f3tese ou outro material como gaze no lugar do globo ocular. Para o fechamento das p\u00e1lpebras, pode ser usada uma cola apropriada ou pontos internos (n\u00e3o aparentes), de forma que o doador permane\u00e7a com o mesmo aspecto, sem qualquer deformidade.<\/p>\n<p>Para a doa\u00e7\u00e3o de tecidos musculoesquel\u00e9ticos, s\u00e3o retirados principalmente ossos do bra\u00e7o (\u00famero) e da coxa (f\u00eamur), al\u00e9m de cartilagens e tend\u00f5es. Em seguida, a equipe reconstitui o corpo do doador com pr\u00f3teses apropriadas, refazendo as juntas do joelho, quadril, ombro e cotovelo.<\/p>\n<p>Por fim, para a doa\u00e7\u00e3o de pele, \u00e9 retirada somente uma fina por\u00e7\u00e3o da pele do dorso das costas e das coxas, sem altera\u00e7\u00f5es na apar\u00eancia do doador falecido.<\/p>\n<h2>\u00c9 poss\u00edvel escolher o receptor?<\/h2>\n<p>Na doa\u00e7\u00e3o em vida, sim \u2013 desde que atendida a legisla\u00e7\u00e3o vigente.<\/p>\n<p>Na doa\u00e7\u00e3o ap\u00f3s a morte, nem o doador, nem a fam\u00edlia podem escolher o receptor. Ele ser\u00e1 sempre o pr\u00f3ximo da lista \u00fanica de espera de cada \u00f3rg\u00e3o ou tecido, dentro da \u00e1rea de abrang\u00eancia da central estadual de transplantes.<\/p>\n<h2>O que \u00e9 morte encef\u00e1lica?<\/h2>\n<p>\u00c9 a parada definitiva e irrevers\u00edvel do enc\u00e9falo, provocando, em poucos minutos, a fal\u00eancia de todo o organismo. O enc\u00e9falo inclui o c\u00e9rebro e o tronco cerebral ou tronco encef\u00e1lico. Ele \u00e9 respons\u00e1vel pelas fun\u00e7\u00f5es essenciais do organismo, como o controle da press\u00e3o, da temperatura e da respira\u00e7\u00e3o, dentre outras.<\/p>\n<p>Ap\u00f3s algumas agress\u00f5es neurol\u00f3gicas, c\u00e9lulas do c\u00e9rebro podem morrer e deixar de cumprir essas fun\u00e7\u00f5es, apresentando um quadro irrevers\u00edvel. Aparelhos e rem\u00e9dios podem manter a respira\u00e7\u00e3o e a press\u00e3o do paciente, mas por um espa\u00e7o curto de tempo.<\/p>\n<p>Quando constatada a morte encef\u00e1lica, o quadro basicamente significa que a pessoa est\u00e1 morta. Nessa situa\u00e7\u00e3o, os \u00f3rg\u00e3os podem ser doados para transplante, se a fam\u00edlia consentir. Se n\u00e3o houver o consentimento, os aparelhos ser\u00e3o desligados, j\u00e1 que o indiv\u00edduo est\u00e1 cl\u00ednica e legalmente morto.<\/p>\n<h2>Posso ter certeza do diagn\u00f3stico de morte encef\u00e1lica?<\/h2>\n<p>Sim. O diagn\u00f3stico de morte encef\u00e1lica \u00e9 regulamentado por uma resolu\u00e7\u00e3o do Conselho Federal de Medicina (CFM) e realizado por meio de exames espec\u00edficos, al\u00e9m da avalia\u00e7\u00e3o de dois m\u00e9dicos distintos.<\/p>\n<p>O intervalo m\u00ednimo de tempo a ser observado entre os exames cl\u00ednicos \u00e9 de no m\u00ednimo uma hora em pacientes a partir de 2 anos. Al\u00e9m disso, \u00e9 obrigat\u00f3ria a confirma\u00e7\u00e3o do diagn\u00f3stico por, pelo menos, um dos seguintes exames complementares: angiografia cerebral, cintilografia cerebral, ultrassom com doppler transcraniano ou eletroencefalograma.<\/p>\n<h2>Como o corpo \u00e9 mantido ap\u00f3s a morte encef\u00e1lica?<\/h2>\n<p>Para a manuten\u00e7\u00e3o hemodin\u00e2mica do corpo ap\u00f3s a morte encef\u00e1lica, o cora\u00e7\u00e3o \u00e9 induzido a funcionar por meio da administra\u00e7\u00e3o de medicamentos; o pulm\u00e3o funciona com a ajuda de aparelhos; e o corpo continua sendo alimentado por via endovenosa.<\/p>\n<h2>Morte encef\u00e1lica \u00e9 o mesmo que coma?<\/h2>\n<p>N\u00e3o. A morte do enc\u00e9falo n\u00e3o \u00e9 a mesma coisa que o coma. Algumas pessoas confundem morte encef\u00e1lica com coma, mas as condi\u00e7\u00f5es s\u00e3o completamente diferentes.<\/p>\n<p>O coma \u00e9 revers\u00edvel, ou seja, a pessoa ainda pode acordar.<\/p>\n<p>J\u00e1 no caso de um paciente com morte encef\u00e1lica, n\u00e3o h\u00e1 possibilidade de acordar novamente, j\u00e1 que o c\u00e9rebro para de funcionar e o sangue deixa de circular, n\u00e3o levando mais oxig\u00eanio para as c\u00e9lulas e acarretando perda irrevers\u00edvel das fun\u00e7\u00f5es cerebrais.<\/p>\n<p>By: miradouronoticias.com.br\/ ag\u00eancia Brasil<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><\/main><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A cada 14 pessoas que manifestam interesse em doar \u00f3rg\u00e3os no Brasil, apenas quatro efetuam a doa\u00e7\u00e3o. De acordo com o Minist\u00e9rio da Sa\u00fade, um dos principais obst\u00e1culos \u00e9 a recusa familiar. Por esse motivo, no Dia Nacional da Doa\u00e7\u00e3o de \u00d3rg\u00e3os, lembrado nesta sexta-feira (27), a pasta encabe\u00e7a uma campanha com o tema Doa\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":25858,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,22],"tags":[],"class_list":["post-25857","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque-principal","category-saude"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Doa\u00e7\u00e3o de \u00f3rg\u00e3os: conhe\u00e7a exig\u00eancias e tire d\u00favidas sobre transplantes - Miradouro Not\u00edcias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/miradouronoticias.com\/site\/2024\/09\/28\/doacao-de-orgaos-conheca-exigencias-e-tire-duvidas-sobre-transplantes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Doa\u00e7\u00e3o de \u00f3rg\u00e3os: conhe\u00e7a exig\u00eancias e tire d\u00favidas sobre transplantes - Miradouro Not\u00edcias\" \/>\n<meta property=\"og:description\" content=\"A cada 14 pessoas que manifestam interesse em doar \u00f3rg\u00e3os no Brasil, apenas quatro efetuam a doa\u00e7\u00e3o. De acordo com o Minist\u00e9rio da Sa\u00fade, um dos principais obst\u00e1culos \u00e9 a recusa familiar. Por esse motivo, no Dia Nacional da Doa\u00e7\u00e3o de \u00d3rg\u00e3os, lembrado nesta sexta-feira (27), a pasta encabe\u00e7a uma campanha com o tema Doa\u00e7\u00e3o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/miradouronoticias.com\/site\/2024\/09\/28\/doacao-de-orgaos-conheca-exigencias-e-tire-duvidas-sobre-transplantes\/\" \/>\n<meta property=\"og:site_name\" content=\"Miradouro Not\u00edcias\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-28T10:56:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2024\/09\/5190610858_3e7437a7e6_c_0.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Cl\u00e1udia Olyver\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cl\u00e1udia Olyver\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2024\\\/09\\\/28\\\/doacao-de-orgaos-conheca-exigencias-e-tire-duvidas-sobre-transplantes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2024\\\/09\\\/28\\\/doacao-de-orgaos-conheca-exigencias-e-tire-duvidas-sobre-transplantes\\\/\"},\"author\":{\"name\":\"Cl\u00e1udia Olyver\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#\\\/schema\\\/person\\\/73440d8c82222950df86f3e1a16aad3b\"},\"headline\":\"Doa\u00e7\u00e3o de \u00f3rg\u00e3os: conhe\u00e7a exig\u00eancias e tire d\u00favidas sobre transplantes\",\"datePublished\":\"2024-09-28T10:56:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2024\\\/09\\\/28\\\/doacao-de-orgaos-conheca-exigencias-e-tire-duvidas-sobre-transplantes\\\/\"},\"wordCount\":2504,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2024\\\/09\\\/28\\\/doacao-de-orgaos-conheca-exigencias-e-tire-duvidas-sobre-transplantes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/5190610858_3e7437a7e6_c_0.webp\",\"articleSection\":[\"Destaque Principal\",\"Sa\u00fade\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2024\\\/09\\\/28\\\/doacao-de-orgaos-conheca-exigencias-e-tire-duvidas-sobre-transplantes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2024\\\/09\\\/28\\\/doacao-de-orgaos-conheca-exigencias-e-tire-duvidas-sobre-transplantes\\\/\",\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2024\\\/09\\\/28\\\/doacao-de-orgaos-conheca-exigencias-e-tire-duvidas-sobre-transplantes\\\/\",\"name\":\"Doa\u00e7\u00e3o de \u00f3rg\u00e3os: conhe\u00e7a exig\u00eancias e tire d\u00favidas sobre transplantes - Miradouro Not\u00edcias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2024\\\/09\\\/28\\\/doacao-de-orgaos-conheca-exigencias-e-tire-duvidas-sobre-transplantes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2024\\\/09\\\/28\\\/doacao-de-orgaos-conheca-exigencias-e-tire-duvidas-sobre-transplantes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/5190610858_3e7437a7e6_c_0.webp\",\"datePublished\":\"2024-09-28T10:56:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2024\\\/09\\\/28\\\/doacao-de-orgaos-conheca-exigencias-e-tire-duvidas-sobre-transplantes\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2024\\\/09\\\/28\\\/doacao-de-orgaos-conheca-exigencias-e-tire-duvidas-sobre-transplantes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2024\\\/09\\\/28\\\/doacao-de-orgaos-conheca-exigencias-e-tire-duvidas-sobre-transplantes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/5190610858_3e7437a7e6_c_0.webp\",\"contentUrl\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/5190610858_3e7437a7e6_c_0.webp\",\"width\":1170,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2024\\\/09\\\/28\\\/doacao-de-orgaos-conheca-exigencias-e-tire-duvidas-sobre-transplantes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Doa\u00e7\u00e3o de \u00f3rg\u00e3os: conhe\u00e7a exig\u00eancias e tire d\u00favidas sobre transplantes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/\",\"name\":\"Miradouro Not\u00edcias\",\"description\":\"Informa\u00e7\u00f5es da cidade e regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#organization\",\"name\":\"Miradouro Not\u00edcias\",\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logomarcamiradouronoticias.png\",\"contentUrl\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logomarcamiradouronoticias.png\",\"width\":747,\"height\":263,\"caption\":\"Miradouro Not\u00edcias\"},\"image\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#\\\/schema\\\/person\\\/73440d8c82222950df86f3e1a16aad3b\",\"name\":\"Cl\u00e1udia Olyver\",\"sameAs\":[\"http:\\\/\\\/www.miradouronoticias.com\"],\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/author\\\/claudia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Doa\u00e7\u00e3o de \u00f3rg\u00e3os: conhe\u00e7a exig\u00eancias e tire d\u00favidas sobre transplantes - Miradouro Not\u00edcias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/miradouronoticias.com\/site\/2024\/09\/28\/doacao-de-orgaos-conheca-exigencias-e-tire-duvidas-sobre-transplantes\/","og_locale":"pt_BR","og_type":"article","og_title":"Doa\u00e7\u00e3o de \u00f3rg\u00e3os: conhe\u00e7a exig\u00eancias e tire d\u00favidas sobre transplantes - Miradouro Not\u00edcias","og_description":"A cada 14 pessoas que manifestam interesse em doar \u00f3rg\u00e3os no Brasil, apenas quatro efetuam a doa\u00e7\u00e3o. De acordo com o Minist\u00e9rio da Sa\u00fade, um dos principais obst\u00e1culos \u00e9 a recusa familiar. Por esse motivo, no Dia Nacional da Doa\u00e7\u00e3o de \u00d3rg\u00e3os, lembrado nesta sexta-feira (27), a pasta encabe\u00e7a uma campanha com o tema Doa\u00e7\u00e3o [&hellip;]","og_url":"https:\/\/miradouronoticias.com\/site\/2024\/09\/28\/doacao-de-orgaos-conheca-exigencias-e-tire-duvidas-sobre-transplantes\/","og_site_name":"Miradouro Not\u00edcias","article_published_time":"2024-09-28T10:56:41+00:00","og_image":[{"width":1170,"height":700,"url":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2024\/09\/5190610858_3e7437a7e6_c_0.webp","type":"image\/webp"}],"author":"Cl\u00e1udia Olyver","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Cl\u00e1udia Olyver","Est. tempo de leitura":"13 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/miradouronoticias.com\/site\/2024\/09\/28\/doacao-de-orgaos-conheca-exigencias-e-tire-duvidas-sobre-transplantes\/#article","isPartOf":{"@id":"https:\/\/miradouronoticias.com\/site\/2024\/09\/28\/doacao-de-orgaos-conheca-exigencias-e-tire-duvidas-sobre-transplantes\/"},"author":{"name":"Cl\u00e1udia Olyver","@id":"https:\/\/miradouronoticias.com\/site\/#\/schema\/person\/73440d8c82222950df86f3e1a16aad3b"},"headline":"Doa\u00e7\u00e3o de \u00f3rg\u00e3os: conhe\u00e7a exig\u00eancias e tire d\u00favidas sobre transplantes","datePublished":"2024-09-28T10:56:41+00:00","mainEntityOfPage":{"@id":"https:\/\/miradouronoticias.com\/site\/2024\/09\/28\/doacao-de-orgaos-conheca-exigencias-e-tire-duvidas-sobre-transplantes\/"},"wordCount":2504,"commentCount":0,"publisher":{"@id":"https:\/\/miradouronoticias.com\/site\/#organization"},"image":{"@id":"https:\/\/miradouronoticias.com\/site\/2024\/09\/28\/doacao-de-orgaos-conheca-exigencias-e-tire-duvidas-sobre-transplantes\/#primaryimage"},"thumbnailUrl":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2024\/09\/5190610858_3e7437a7e6_c_0.webp","articleSection":["Destaque Principal","Sa\u00fade"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/miradouronoticias.com\/site\/2024\/09\/28\/doacao-de-orgaos-conheca-exigencias-e-tire-duvidas-sobre-transplantes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/miradouronoticias.com\/site\/2024\/09\/28\/doacao-de-orgaos-conheca-exigencias-e-tire-duvidas-sobre-transplantes\/","url":"https:\/\/miradouronoticias.com\/site\/2024\/09\/28\/doacao-de-orgaos-conheca-exigencias-e-tire-duvidas-sobre-transplantes\/","name":"Doa\u00e7\u00e3o de \u00f3rg\u00e3os: conhe\u00e7a exig\u00eancias e tire d\u00favidas sobre transplantes - Miradouro Not\u00edcias","isPartOf":{"@id":"https:\/\/miradouronoticias.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/miradouronoticias.com\/site\/2024\/09\/28\/doacao-de-orgaos-conheca-exigencias-e-tire-duvidas-sobre-transplantes\/#primaryimage"},"image":{"@id":"https:\/\/miradouronoticias.com\/site\/2024\/09\/28\/doacao-de-orgaos-conheca-exigencias-e-tire-duvidas-sobre-transplantes\/#primaryimage"},"thumbnailUrl":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2024\/09\/5190610858_3e7437a7e6_c_0.webp","datePublished":"2024-09-28T10:56:41+00:00","breadcrumb":{"@id":"https:\/\/miradouronoticias.com\/site\/2024\/09\/28\/doacao-de-orgaos-conheca-exigencias-e-tire-duvidas-sobre-transplantes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/miradouronoticias.com\/site\/2024\/09\/28\/doacao-de-orgaos-conheca-exigencias-e-tire-duvidas-sobre-transplantes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/miradouronoticias.com\/site\/2024\/09\/28\/doacao-de-orgaos-conheca-exigencias-e-tire-duvidas-sobre-transplantes\/#primaryimage","url":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2024\/09\/5190610858_3e7437a7e6_c_0.webp","contentUrl":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2024\/09\/5190610858_3e7437a7e6_c_0.webp","width":1170,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/miradouronoticias.com\/site\/2024\/09\/28\/doacao-de-orgaos-conheca-exigencias-e-tire-duvidas-sobre-transplantes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/miradouronoticias.com\/site\/"},{"@type":"ListItem","position":2,"name":"Doa\u00e7\u00e3o de \u00f3rg\u00e3os: conhe\u00e7a exig\u00eancias e tire d\u00favidas sobre transplantes"}]},{"@type":"WebSite","@id":"https:\/\/miradouronoticias.com\/site\/#website","url":"https:\/\/miradouronoticias.com\/site\/","name":"Miradouro Not\u00edcias","description":"Informa\u00e7\u00f5es da cidade e regi\u00e3o","publisher":{"@id":"https:\/\/miradouronoticias.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/miradouronoticias.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/miradouronoticias.com\/site\/#organization","name":"Miradouro Not\u00edcias","url":"https:\/\/miradouronoticias.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/miradouronoticias.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2022\/01\/logomarcamiradouronoticias.png","contentUrl":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2022\/01\/logomarcamiradouronoticias.png","width":747,"height":263,"caption":"Miradouro Not\u00edcias"},"image":{"@id":"https:\/\/miradouronoticias.com\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/miradouronoticias.com\/site\/#\/schema\/person\/73440d8c82222950df86f3e1a16aad3b","name":"Cl\u00e1udia Olyver","sameAs":["http:\/\/www.miradouronoticias.com"],"url":"https:\/\/miradouronoticias.com\/site\/author\/claudia\/"}]}},"_links":{"self":[{"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/posts\/25857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/comments?post=25857"}],"version-history":[{"count":1,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/posts\/25857\/revisions"}],"predecessor-version":[{"id":25859,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/posts\/25857\/revisions\/25859"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/media\/25858"}],"wp:attachment":[{"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/media?parent=25857"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/categories?post=25857"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/tags?post=25857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}