{"id":25824,"date":"2024-09-25T08:04:44","date_gmt":"2024-09-25T11:04:44","guid":{"rendered":"https:\/\/miradouronoticias.com\/site\/?p=25824"},"modified":"2024-09-25T08:04:44","modified_gmt":"2024-09-25T11:04:44","slug":"tse-aprova-uso-da-forca-federal-nas-eleicoes-em-cidades-de-12-estados","status":"publish","type":"post","link":"https:\/\/miradouronoticias.com\/site\/2024\/09\/25\/tse-aprova-uso-da-forca-federal-nas-eleicoes-em-cidades-de-12-estados\/","title":{"rendered":"TSE aprova uso da for\u00e7a federal nas elei\u00e7\u00f5es em cidades de 12 estados"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-25825\" src=\"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2024\/09\/52756474235_962c78f617_o-300x179.webp\" alt=\"\" width=\"300\" height=\"179\" srcset=\"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2024\/09\/52756474235_962c78f617_o-300x179.webp 300w, https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2024\/09\/52756474235_962c78f617_o-1024x613.webp 1024w, https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2024\/09\/52756474235_962c78f617_o-768x459.webp 768w, https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2024\/09\/52756474235_962c78f617_o.webp 1170w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>O Tribunal Superior Eleitoral (TSE) aprovou nesta ter\u00e7a-feira (24) o envio de militares federais para realizar a seguran\u00e7a de locais de vota\u00e7\u00e3o no primeiro turno das elei\u00e7\u00f5es municipais, que ser\u00e1 realizado no dia 6 de outubro.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1613561&amp;o=node\" \/><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1613561&amp;o=node\" \/><\/p>\n<p>Por unanimidade, os ministros aprovaram um pacote de 53 processos para garantir o envio de soldados das For\u00e7as Armadas para munic\u00edpios dos estados de Tocantins, Piau\u00ed, Rio de Janeiro, Mato Grosso do Sul, Amazonas, Cear\u00e1, Maranh\u00e3o, Acre, Mato Grosso, Par\u00e1, Para\u00edba e Rio Grande do Norte.<\/p>\n<p>Durante a sess\u00e3o, a presidente do TSE, C\u00e1rmen L\u00facia, destacou que a requisi\u00e7\u00e3o de for\u00e7as federais \u00e9 um procedimento comum que ocorre em todas as elei\u00e7\u00f5es.<\/p>\n<p>&#8220;Os governadores comunicam aos tribunais regionais eleitorais (TREs) que eles precisam de for\u00e7as federais para garantir a vota\u00e7\u00e3o e a apura\u00e7\u00e3o&#8221;, ressaltou a ministra.<\/p>\n<p>O envio de tropas federais ocorre quando um munic\u00edpio informa \u00e0 Justi\u00e7a Eleitoral que n\u00e3o tem capacidade de garantir a normalidade do pleito com o efetivo policial local.<\/p>\n<p>By: miradouronoticias.com.br\/ ag\u00eancia brasil<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Tribunal Superior Eleitoral (TSE) aprovou nesta ter\u00e7a-feira (24) o envio de militares federais para realizar a seguran\u00e7a de locais de vota\u00e7\u00e3o no primeiro turno das elei\u00e7\u00f5es municipais, que ser\u00e1 realizado no dia 6 de outubro. Por unanimidade, os ministros aprovaram um pacote de 53 processos para garantir o envio de soldados das For\u00e7as Armadas [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":25825,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,17],"tags":[],"class_list":["post-25824","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque-principal","category-politica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TSE aprova uso da for\u00e7a federal nas elei\u00e7\u00f5es em cidades de 12 estados - Miradouro Not\u00edcias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/miradouronoticias.com\/site\/2024\/09\/25\/tse-aprova-uso-da-forca-federal-nas-eleicoes-em-cidades-de-12-estados\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TSE aprova uso da for\u00e7a federal nas elei\u00e7\u00f5es em cidades de 12 estados - Miradouro Not\u00edcias\" \/>\n<meta property=\"og:description\" content=\"O Tribunal Superior Eleitoral (TSE) aprovou nesta ter\u00e7a-feira (24) o envio de militares federais para realizar a seguran\u00e7a de locais de vota\u00e7\u00e3o no primeiro turno das elei\u00e7\u00f5es municipais, que ser\u00e1 realizado no dia 6 de outubro. Por unanimidade, os ministros aprovaram um pacote de 53 processos para garantir o envio de soldados das For\u00e7as Armadas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/miradouronoticias.com\/site\/2024\/09\/25\/tse-aprova-uso-da-forca-federal-nas-eleicoes-em-cidades-de-12-estados\/\" \/>\n<meta property=\"og:site_name\" content=\"Miradouro Not\u00edcias\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-25T11:04:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2024\/09\/52756474235_962c78f617_o.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Cl\u00e1udia Olyver\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cl\u00e1udia Olyver\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2024\\\/09\\\/25\\\/tse-aprova-uso-da-forca-federal-nas-eleicoes-em-cidades-de-12-estados\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2024\\\/09\\\/25\\\/tse-aprova-uso-da-forca-federal-nas-eleicoes-em-cidades-de-12-estados\\\/\"},\"author\":{\"name\":\"Cl\u00e1udia Olyver\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#\\\/schema\\\/person\\\/73440d8c82222950df86f3e1a16aad3b\"},\"headline\":\"TSE aprova uso da for\u00e7a federal nas elei\u00e7\u00f5es em cidades de 12 estados\",\"datePublished\":\"2024-09-25T11:04:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2024\\\/09\\\/25\\\/tse-aprova-uso-da-forca-federal-nas-eleicoes-em-cidades-de-12-estados\\\/\"},\"wordCount\":196,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2024\\\/09\\\/25\\\/tse-aprova-uso-da-forca-federal-nas-eleicoes-em-cidades-de-12-estados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/52756474235_962c78f617_o.webp\",\"articleSection\":[\"Destaque Principal\",\"Pol\u00edtica\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2024\\\/09\\\/25\\\/tse-aprova-uso-da-forca-federal-nas-eleicoes-em-cidades-de-12-estados\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2024\\\/09\\\/25\\\/tse-aprova-uso-da-forca-federal-nas-eleicoes-em-cidades-de-12-estados\\\/\",\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2024\\\/09\\\/25\\\/tse-aprova-uso-da-forca-federal-nas-eleicoes-em-cidades-de-12-estados\\\/\",\"name\":\"TSE aprova uso da for\u00e7a federal nas elei\u00e7\u00f5es em cidades de 12 estados - Miradouro Not\u00edcias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2024\\\/09\\\/25\\\/tse-aprova-uso-da-forca-federal-nas-eleicoes-em-cidades-de-12-estados\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2024\\\/09\\\/25\\\/tse-aprova-uso-da-forca-federal-nas-eleicoes-em-cidades-de-12-estados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/52756474235_962c78f617_o.webp\",\"datePublished\":\"2024-09-25T11:04:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2024\\\/09\\\/25\\\/tse-aprova-uso-da-forca-federal-nas-eleicoes-em-cidades-de-12-estados\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2024\\\/09\\\/25\\\/tse-aprova-uso-da-forca-federal-nas-eleicoes-em-cidades-de-12-estados\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2024\\\/09\\\/25\\\/tse-aprova-uso-da-forca-federal-nas-eleicoes-em-cidades-de-12-estados\\\/#primaryimage\",\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/52756474235_962c78f617_o.webp\",\"contentUrl\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/52756474235_962c78f617_o.webp\",\"width\":1170,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2024\\\/09\\\/25\\\/tse-aprova-uso-da-forca-federal-nas-eleicoes-em-cidades-de-12-estados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TSE aprova uso da for\u00e7a federal nas elei\u00e7\u00f5es em cidades de 12 estados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/\",\"name\":\"Miradouro Not\u00edcias\",\"description\":\"Informa\u00e7\u00f5es da cidade e regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#organization\",\"name\":\"Miradouro Not\u00edcias\",\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logomarcamiradouronoticias.png\",\"contentUrl\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logomarcamiradouronoticias.png\",\"width\":747,\"height\":263,\"caption\":\"Miradouro Not\u00edcias\"},\"image\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#\\\/schema\\\/person\\\/73440d8c82222950df86f3e1a16aad3b\",\"name\":\"Cl\u00e1udia Olyver\",\"sameAs\":[\"http:\\\/\\\/www.miradouronoticias.com\"],\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/author\\\/claudia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TSE aprova uso da for\u00e7a federal nas elei\u00e7\u00f5es em cidades de 12 estados - Miradouro Not\u00edcias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/miradouronoticias.com\/site\/2024\/09\/25\/tse-aprova-uso-da-forca-federal-nas-eleicoes-em-cidades-de-12-estados\/","og_locale":"pt_BR","og_type":"article","og_title":"TSE aprova uso da for\u00e7a federal nas elei\u00e7\u00f5es em cidades de 12 estados - Miradouro Not\u00edcias","og_description":"O Tribunal Superior Eleitoral (TSE) aprovou nesta ter\u00e7a-feira (24) o envio de militares federais para realizar a seguran\u00e7a de locais de vota\u00e7\u00e3o no primeiro turno das elei\u00e7\u00f5es municipais, que ser\u00e1 realizado no dia 6 de outubro. Por unanimidade, os ministros aprovaram um pacote de 53 processos para garantir o envio de soldados das For\u00e7as Armadas [&hellip;]","og_url":"https:\/\/miradouronoticias.com\/site\/2024\/09\/25\/tse-aprova-uso-da-forca-federal-nas-eleicoes-em-cidades-de-12-estados\/","og_site_name":"Miradouro Not\u00edcias","article_published_time":"2024-09-25T11:04:44+00:00","og_image":[{"width":1170,"height":700,"url":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2024\/09\/52756474235_962c78f617_o.webp","type":"image\/webp"}],"author":"Cl\u00e1udia Olyver","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Cl\u00e1udia Olyver","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/miradouronoticias.com\/site\/2024\/09\/25\/tse-aprova-uso-da-forca-federal-nas-eleicoes-em-cidades-de-12-estados\/#article","isPartOf":{"@id":"https:\/\/miradouronoticias.com\/site\/2024\/09\/25\/tse-aprova-uso-da-forca-federal-nas-eleicoes-em-cidades-de-12-estados\/"},"author":{"name":"Cl\u00e1udia Olyver","@id":"https:\/\/miradouronoticias.com\/site\/#\/schema\/person\/73440d8c82222950df86f3e1a16aad3b"},"headline":"TSE aprova uso da for\u00e7a federal nas elei\u00e7\u00f5es em cidades de 12 estados","datePublished":"2024-09-25T11:04:44+00:00","mainEntityOfPage":{"@id":"https:\/\/miradouronoticias.com\/site\/2024\/09\/25\/tse-aprova-uso-da-forca-federal-nas-eleicoes-em-cidades-de-12-estados\/"},"wordCount":196,"commentCount":0,"publisher":{"@id":"https:\/\/miradouronoticias.com\/site\/#organization"},"image":{"@id":"https:\/\/miradouronoticias.com\/site\/2024\/09\/25\/tse-aprova-uso-da-forca-federal-nas-eleicoes-em-cidades-de-12-estados\/#primaryimage"},"thumbnailUrl":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2024\/09\/52756474235_962c78f617_o.webp","articleSection":["Destaque Principal","Pol\u00edtica"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/miradouronoticias.com\/site\/2024\/09\/25\/tse-aprova-uso-da-forca-federal-nas-eleicoes-em-cidades-de-12-estados\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/miradouronoticias.com\/site\/2024\/09\/25\/tse-aprova-uso-da-forca-federal-nas-eleicoes-em-cidades-de-12-estados\/","url":"https:\/\/miradouronoticias.com\/site\/2024\/09\/25\/tse-aprova-uso-da-forca-federal-nas-eleicoes-em-cidades-de-12-estados\/","name":"TSE aprova uso da for\u00e7a federal nas elei\u00e7\u00f5es em cidades de 12 estados - Miradouro Not\u00edcias","isPartOf":{"@id":"https:\/\/miradouronoticias.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/miradouronoticias.com\/site\/2024\/09\/25\/tse-aprova-uso-da-forca-federal-nas-eleicoes-em-cidades-de-12-estados\/#primaryimage"},"image":{"@id":"https:\/\/miradouronoticias.com\/site\/2024\/09\/25\/tse-aprova-uso-da-forca-federal-nas-eleicoes-em-cidades-de-12-estados\/#primaryimage"},"thumbnailUrl":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2024\/09\/52756474235_962c78f617_o.webp","datePublished":"2024-09-25T11:04:44+00:00","breadcrumb":{"@id":"https:\/\/miradouronoticias.com\/site\/2024\/09\/25\/tse-aprova-uso-da-forca-federal-nas-eleicoes-em-cidades-de-12-estados\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/miradouronoticias.com\/site\/2024\/09\/25\/tse-aprova-uso-da-forca-federal-nas-eleicoes-em-cidades-de-12-estados\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/miradouronoticias.com\/site\/2024\/09\/25\/tse-aprova-uso-da-forca-federal-nas-eleicoes-em-cidades-de-12-estados\/#primaryimage","url":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2024\/09\/52756474235_962c78f617_o.webp","contentUrl":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2024\/09\/52756474235_962c78f617_o.webp","width":1170,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/miradouronoticias.com\/site\/2024\/09\/25\/tse-aprova-uso-da-forca-federal-nas-eleicoes-em-cidades-de-12-estados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/miradouronoticias.com\/site\/"},{"@type":"ListItem","position":2,"name":"TSE aprova uso da for\u00e7a federal nas elei\u00e7\u00f5es em cidades de 12 estados"}]},{"@type":"WebSite","@id":"https:\/\/miradouronoticias.com\/site\/#website","url":"https:\/\/miradouronoticias.com\/site\/","name":"Miradouro Not\u00edcias","description":"Informa\u00e7\u00f5es da cidade e regi\u00e3o","publisher":{"@id":"https:\/\/miradouronoticias.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/miradouronoticias.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/miradouronoticias.com\/site\/#organization","name":"Miradouro Not\u00edcias","url":"https:\/\/miradouronoticias.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/miradouronoticias.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2022\/01\/logomarcamiradouronoticias.png","contentUrl":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2022\/01\/logomarcamiradouronoticias.png","width":747,"height":263,"caption":"Miradouro Not\u00edcias"},"image":{"@id":"https:\/\/miradouronoticias.com\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/miradouronoticias.com\/site\/#\/schema\/person\/73440d8c82222950df86f3e1a16aad3b","name":"Cl\u00e1udia Olyver","sameAs":["http:\/\/www.miradouronoticias.com"],"url":"https:\/\/miradouronoticias.com\/site\/author\/claudia\/"}]}},"_links":{"self":[{"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/posts\/25824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/comments?post=25824"}],"version-history":[{"count":1,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/posts\/25824\/revisions"}],"predecessor-version":[{"id":25826,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/posts\/25824\/revisions\/25826"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/media\/25825"}],"wp:attachment":[{"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/media?parent=25824"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/categories?post=25824"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/tags?post=25824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}