{"id":15658,"date":"2023-06-26T04:24:29","date_gmt":"2023-06-26T07:24:29","guid":{"rendered":"https:\/\/miradouronoticias.com\/site\/?p=15658"},"modified":"2023-06-26T04:24:29","modified_gmt":"2023-06-26T07:24:29","slug":"reajustes-das-mensalidades-deixam-estudantes-sem-opcao","status":"publish","type":"post","link":"https:\/\/miradouronoticias.com\/site\/2023\/06\/26\/reajustes-das-mensalidades-deixam-estudantes-sem-opcao\/","title":{"rendered":"Reajustes das mensalidades deixam estudantes sem op\u00e7\u00e3o"},"content":{"rendered":"<h3 class=\"col-10 offset-1 animated fadeInDown dealy-900 display-8 display-md-8 alt-font font-italic my-1 text-center\">UNE defende mudan\u00e7as no Fundo de Financiamento Estudantil<\/h3>\n<div class=\"col-lg-12 mb-3\">\n<div class=\"row\">\n<div id=\"tts-container\" class=\"col-xl-7 offset-xl-1 col-lg-8 offset-lg-0 col-md-10 offset-md-1 mb-3\">\n<p><audio id=\"tts-player\" src=\"https:\/\/tts-app.ebc.com.br\/media\/tts\/205502.mp3\" controls=\"controls\" data-mce-fragment=\"1\"><\/audio><\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"col-xl-7 offset-xl-1 col-lg-8 offset-lg-0 col-md-10 offset-md-1 mb-3\">\n<div class=\"post-item alt-font\">\n<div class=\"post-item-wrap\">\n<p>Os recentes reajustes das mensalidades do ensino superior podem deixar v\u00e1rios estudantes de fora da faculdade, por n\u00e3o terem condi\u00e7\u00f5es de pagar, de acordo com estudo feito pela Quero Educa\u00e7\u00e3o. O levantamento mostra que enquanto os futuros alunos buscam mensalidades de cerca de R$ 500, a m\u00e9dia cobrada pelas institui\u00e7\u00f5es \u00e9 R$ 722. Isso faz com que 68% daqueles que est\u00e3o em busca de uma forma\u00e7\u00e3o superior n\u00e3o encontrem op\u00e7\u00f5es vi\u00e1veis.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1540160&amp;o=node\" \/><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1540160&amp;o=node\" \/><\/p>\n<p>O levantamento foi realizado a partir das buscas feitas na plataforma Quero Bolsa, um dos bra\u00e7os da Quero Educa\u00e7\u00e3o. Pela plataforma, estudantes podem obter bolsas de estudos de 5% a 80% de desconto em institui\u00e7\u00f5es privadas. Hoje, as bolsas ofertadas cobrem, de acordo com a Quero, 10% das matr\u00edculas nas faculdades. Mais de 1,3 mil institui\u00e7\u00f5es ofertam bolsas de estudo pela plataforma.<\/p>\n<p>Segundo a Quero Educa\u00e7\u00e3o, no in\u00edcio deste ano as maiores institui\u00e7\u00f5es do mercado praticavam, na plataforma, um pre\u00e7o m\u00e9dio nas mensalidades de R$ 530, enquanto os alunos buscavam cursos com pre\u00e7o m\u00e9dio de R$ 526. Ao longo do ano, em meio \u00e0 queda no poder de compra, os estudantes passaram a buscar gradua\u00e7\u00f5es presenciais com um pre\u00e7o m\u00e9dio de R$ 495, enquanto o valor m\u00e9dio das mensalidades ofertadas na plataforma foi elevado para R$ 722, representando um aumento de 45% em rela\u00e7\u00e3o a faixa buscada pelos alunos.<\/p>\n<p>Se antes as institui\u00e7\u00f5es atendiam a 63% dos estudantes que buscavam vagas, agora essa porcentagem caiu para 32%. \u201cN\u00e3o houve aumento do poder de compra dos alunos, eles n\u00e3o podem pagar esse pre\u00e7o. \u00c9 isso que a gente vem alertando. Est\u00e1 ficando muita gente de fora. E o fato \u00e9 que as institui\u00e7\u00f5es n\u00e3o v\u00e3o conseguir encher as suas salas\u201d, alerta o diretor da Quero Educa\u00e7\u00e3o, Marcelo Lima.<\/p>\n<header class=\"header-static navbar-sticky navbar-light navbar-sticky-on\">\n<nav class=\"navbar\">\n<div class=\"container nav-item dropdown megamenu\">\n<div class=\"offset-1 navbar-brand flex-grow-1\"><\/div>\n<div class=\"pos-absolute-center\"><a class=\"\" href=\"https:\/\/agenciabrasil.ebc.com.br\/\"><img decoding=\"async\" class=\"navbar-brand-item m-auto\" src=\"https:\/\/cdn.jsdelivr.net\/gh\/regiosousa\/ebc-assets@master\/images\/logo-agenciabrasil.svg\" alt=\"Logo Ag\u00eancia Brasil\" height=\"30\" \/><\/a><\/div>\n<div class=\"navbar-nav\"><\/div>\n<div class=\"navbar-nav\">\n<div id=\"search\" class=\"nav-item search border-0 pl-3 pr-0 px-lg-2\"><a class=\"nav-link\" title=\"Abrir a busca no site\" href=\"https:\/\/agenciabrasil.ebc.com.br\/educacao\/noticia\/2023-06\/reajustes-das-mensalidades-deixam-estudantes-sem-opcao#search-open\" data-toggle=\"collapse\"><i class=\"ti-search\"><\/i><span class=\"sr-only\">Abrir O Campo De Busca<\/span><\/a><\/div>\n<\/div>\n<\/div>\n<\/nav>\n<\/header>\n<div class=\"sticky-space\"><\/div>\n<div class=\"container\"><\/div>\n<div class=\"region region-content\">\n<article class=\"container\">\n<div class=\"row\">\n<div class=\"col-lg-12 mb-3\">\n<div class=\"post-image\"><a href=\"https:\/\/agenciabrasil.ebc.com.br\/educacao\/noticia\/2023-06\/reajustes-das-mensalidades-deixam-estudantes-sem-opcao#\"><img decoding=\"async\" id=\"media-273830\" class=\"rounded-lg shadow-sm w-100\" title=\"Valter Campanato\/Ag\u00eancia Brasil\" src=\"https:\/\/imagens.ebc.com.br\/mAzFIVZ1QrIdyQMll6QDBc5AC34=\/1170x700\/smart\/https:\/\/agenciabrasil.ebc.com.br\/sites\/default\/files\/thumbnails\/image\/enem_vac_abr_2811214311.jpg?itok=sOthcv8f\" alt=\"Participantes do Exame Nacional do Ensino M\u00e9dio (Enem) 2021 fazem, neste domingo (28), segundo dia de avalia\u00e7\u00e3o, provas de matem\u00e1tica e de ci\u00eancia da natureza.\" \/>\u00a9 Valter Campanato\/Ag\u00eancia Brasil<\/a><\/div>\n<\/div>\n<div class=\"col-lg-12 mb-3\">\n<div class=\"row\">\n<div class=\"col-10 offset-1 animated fadeInDown dealy-1100 alt-font text-center\"><a href=\"https:\/\/agenciabrasil.ebc.com.br\/educacao\"><span class=\"badge badge-pill badge-primary\">Educa\u00e7\u00e3o<\/span><\/a><\/div>\n<h2 class=\"col-10 offset-1 animated fadeInDown dealy-750 display-6 display-md-4 display-lg-5 font-weight-bold alt-font text-center my-1\">Reajustes das mensalidades deixam estudantes sem op\u00e7\u00e3o<\/h2>\n<h3 class=\"col-10 offset-1 animated fadeInDown dealy-900 display-8 display-md-8 alt-font font-italic my-1 text-center\">UNE defende mudan\u00e7as no Fundo de Financiamento Estudantil<\/h3>\n<\/div>\n<ul class=\"divider social-icons si-border round si-colored-bg-on-hover my-3\">\n<li class=\"social-icons-item social-whatsapp\"><a class=\"social-icons-link click-share\" title=\"Share on WhatsApp\" href=\"https:\/\/api.whatsapp.com\/send?text=Reajustes+das+mensalidades+deixam+estudantes+sem+op%C3%A7%C3%A3o++%7C+Ag%C3%AAncia+Brasil+%7C+Ag%C3%AAncia+Brasil+%7C+https%3A%2F%2Fagenciabrasil.ebc.com.br%2Feducacao%2Fnoticia%2F2023-06%2Freajustes-das-mensalidades-deixam-estudantes-sem-opcao\"><i class=\"fab fa-whatsapp\"><\/i><span class=\"sr-only\">Share on WhatsApp<\/span><\/a><\/li>\n<li class=\"social-icons-item social-facebook\"><a class=\"social-icons-link click-share\" title=\"Share on Facebook\" href=\"https:\/\/facebook.com\/sharer.php?u=https%3A%2F%2Fagenciabrasil.ebc.com.br%2Feducacao%2Fnoticia%2F2023-06%2Freajustes-das-mensalidades-deixam-estudantes-sem-opcao&amp;t=Reajustes+das+mensalidades+deixam+estudantes+sem+op%C3%A7%C3%A3o++%7C+Ag%C3%AAncia+Brasil\"><i class=\"fab fa-facebook-f\"><\/i><span class=\"sr-only\">Share on Facebook<\/span><\/a><\/li>\n<li class=\"social-icons-item social-twitter\"><a class=\"social-icons-link click-share\" title=\"Share on Twitter\" href=\"https:\/\/twitter.com\/intent\/tweet?url=https%3A%2F%2Fagenciabrasil.ebc.com.br%2Feducacao%2Fnoticia%2F2023-06%2Freajustes-das-mensalidades-deixam-estudantes-sem-opcao&amp;text=Reajustes+das+mensalidades+deixam+estudantes+sem+op%C3%A7%C3%A3o++%7C+Ag%C3%AAncia+Brasil\"><i class=\"fab fa-twitter\"><\/i><span class=\"sr-only\">Share on Twitter<\/span><\/a><\/li>\n<li class=\"social-icons-item social-linkedin\"><a class=\"social-icons-link click-share\" title=\"Share on Linkedin\" href=\"http:\/\/www.linkedin.com\/shareArticle?url=https%3A%2F%2Fagenciabrasil.ebc.com.br%2Feducacao%2Fnoticia%2F2023-06%2Freajustes-das-mensalidades-deixam-estudantes-sem-opcao&amp;summary=Reajustes+das+mensalidades+deixam+estudantes+sem+op%C3%A7%C3%A3o++%7C+Ag%C3%AAncia+Brasil\"><i class=\"fab fa-linkedin\"><\/i><span class=\"sr-only\">Share on Linkedin<\/span><\/a><\/li>\n<\/ul>\n<div class=\"row\">\n<h4 class=\"col-10 offset-1 animated fadeInDown dealy-1100 alt-font font-italic my-2 small text-info text-center\">Publicado em 25\/06\/2023 &#8211; 14:25 Por Mariana Tokarnia &#8211; Rep\u00f3rter da Ag\u00eancia Brasil &#8211; Rio de Janeiro<\/h4>\n<div id=\"tts-container\" class=\"col-xl-7 offset-xl-1 col-lg-8 offset-lg-0 col-md-10 offset-md-1 mb-3\">\n<h4 class=\"alt-font font-italic small text-info text-left\">ouvir:<\/h4>\n<p><audio id=\"tts-player\" src=\"https:\/\/tts-app.ebc.com.br\/media\/tts\/205502.mp3\" controls=\"controls\" data-mce-fragment=\"1\"><\/audio><\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"col-xl-7 offset-xl-1 col-lg-8 offset-lg-0 col-md-10 offset-md-1 mb-3\">\n<div class=\"post-item alt-font\">\n<div class=\"post-item-wrap\">\n<p>Os recentes reajustes das mensalidades do ensino superior podem deixar v\u00e1rios estudantes de fora da faculdade, por n\u00e3o terem condi\u00e7\u00f5es de pagar, de acordo com estudo feito pela Quero Educa\u00e7\u00e3o. O levantamento mostra que enquanto os futuros alunos buscam mensalidades de cerca de R$ 500, a m\u00e9dia cobrada pelas institui\u00e7\u00f5es \u00e9 R$ 722. Isso faz com que 68% daqueles que est\u00e3o em busca de uma forma\u00e7\u00e3o superior n\u00e3o encontrem op\u00e7\u00f5es vi\u00e1veis.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1540160&amp;o=node\" \/><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1540160&amp;o=node\" \/><\/p>\n<p>O levantamento foi realizado a partir das buscas feitas na plataforma Quero Bolsa, um dos bra\u00e7os da Quero Educa\u00e7\u00e3o. Pela plataforma, estudantes podem obter bolsas de estudos de 5% a 80% de desconto em institui\u00e7\u00f5es privadas. Hoje, as bolsas ofertadas cobrem, de acordo com a Quero, 10% das matr\u00edculas nas faculdades. Mais de 1,3 mil institui\u00e7\u00f5es ofertam bolsas de estudo pela plataforma.<\/p>\n<p>Segundo a Quero Educa\u00e7\u00e3o, no in\u00edcio deste ano as maiores institui\u00e7\u00f5es do mercado praticavam, na plataforma, um pre\u00e7o m\u00e9dio nas mensalidades de R$ 530, enquanto os alunos buscavam cursos com pre\u00e7o m\u00e9dio de R$ 526. Ao longo do ano, em meio \u00e0 queda no poder de compra, os estudantes passaram a buscar gradua\u00e7\u00f5es presenciais com um pre\u00e7o m\u00e9dio de R$ 495, enquanto o valor m\u00e9dio das mensalidades ofertadas na plataforma foi elevado para R$ 722, representando um aumento de 45% em rela\u00e7\u00e3o a faixa buscada pelos alunos.<\/p>\n<p>Se antes as institui\u00e7\u00f5es atendiam a 63% dos estudantes que buscavam vagas, agora essa porcentagem caiu para 32%. \u201cN\u00e3o houve aumento do poder de compra dos alunos, eles n\u00e3o podem pagar esse pre\u00e7o. \u00c9 isso que a gente vem alertando. Est\u00e1 ficando muita gente de fora. E o fato \u00e9 que as institui\u00e7\u00f5es n\u00e3o v\u00e3o conseguir encher as suas salas\u201d, alerta o diretor da Quero Educa\u00e7\u00e3o, Marcelo Lima.<\/p>\n<p>Para Lima os descontos nas mensalidades e as bolsas de estudos s\u00e3o mais vantajosas que os financiamentos, pois podem garantir a forma\u00e7\u00e3o dos alunos sem que eles fiquem endividados quando deixam a universidade. &#8220;\u00c9 uma grande oportunidade para as faculdades que quiserem trabalhar nesse mercado num pre\u00e7o mais acess\u00edvel para os alunos. \u00c9 uma oportunidade para elas encherem suas salas, porque \u00e9 muito melhor ter uma sala cheia de alunos pagando R$ 500 do que ter uma sala pela metade, conseguindo captar aqueles alunos que est\u00e3o dispostos a pagar R$ 720&#8221;.<\/p>\n<h2>Reajustes necess\u00e1rios<\/h2>\n<p>Entidades representativas do ensino superior reconhecem a dificuldade dos estudantes em pagar as mensalidades, mas ressaltam que os reajustes s\u00e3o necess\u00e1rios, uma vez que muitas das institui\u00e7\u00f5es, durante a pandemia, n\u00e3o aumentaram as mensalidades. \u201cO pre\u00e7o \u00e9 formado com base no custo. Houve, pela infla\u00e7\u00e3o, aumento real de custos nas universidades, aumento de luz, aluguel, corre\u00e7\u00e3o de sal\u00e1rios\u201d, argumenta o diretor presidente da Associa\u00e7\u00e3o Brasileira de Mantenedoras de Ensino Superior (ABMES), Celso Niskier. De acordo com ele, cerca da metade das vagas ofertadas pelas institui\u00e7\u00f5es n\u00e3o s\u00e3o preenchidas.<\/p>\n<p>Segundo o diretor executivo do Semesp, que tamb\u00e9m representa as mantenedoras de ensino superior do Brasil, Rodrigo Capelato, cerca de 30% a 35% dos estudantes t\u00eam atualmente algum desconto ou bolsa. \u201cEm 2023, houve pequena recupera\u00e7\u00e3o do setor, mas sempre com muito desconto, precisando ajustar valores porque o poder aquisitivo ainda est\u00e1 muito baixo e as fam\u00edlias est\u00e3o muito endividadas\u201d, disse.<\/p>\n<p>reclama\u00e7\u00f5es.<\/p>\n<p>Sobre os reajustes, a estudante ressalta que os aumentos est\u00e3o recaindo n\u00e3o apenas para os estudantes que est\u00e3o ingressando na universidade, mas para aqueles que j\u00e1 est\u00e3o matriculados e que acabam n\u00e3o tendo condi\u00e7\u00f5es para se manter estudando.<\/p>\n<p>De acordo com Manuella, a UNE defende, al\u00e9m de um Fies que consiga assegurar que os estudantes concluam os cursos, uma garantia de emprego, para que possam, assim que formados, quitar suas d\u00edvidas com o programa.<\/p>\n<p>\u201cA gente defende o Fies, mas defende que ele consiga garantir o pleno emprego, para que os estudantes consigam ter acesso ao mercado de trabalho. O Fies \u00e9 importante para garantir entrada na universidade, mas que seja um Fies que os estudantes consigam entrar, permanecer e concluir um curso com qualidade, que n\u00e3o o deixem pela metade\u201d, defende.<\/p>\n<h2>Fies<\/h2>\n<p>Atualmente, o Fies est\u00e1 sendo discutido em um grupo de trabalho criado pelo Minist\u00e9rio da Educa\u00e7\u00e3o. As discuss\u00f5es, em tese, terminam em setembro. A Portaria 390, que oficializou o grupo de trabalho, foi publicada no Di\u00e1rio Oficial da Uni\u00e3o (DOU) no dia 8 de mar\u00e7o, com a finalidade de promover estudos t\u00e9cnicos relacionados ao Fundo, como diagn\u00f3sticos sobre a situa\u00e7\u00e3o atual do Fies, a reavalia\u00e7\u00e3o do limite de financiamento e a desburocratiza\u00e7\u00e3o do programa.<\/p>\n<p>Criado em 1999, o Fies oferece financiamento a estudantes de baixa renda em institui\u00e7\u00f5es particulares de ensino a condi\u00e7\u00f5es mais favor\u00e1veis que as de mercado. O programa, que chegou a firmar, em 2014, mais de 732 mil contratos, sofreu, desde 2015, uma s\u00e9rie de mudan\u00e7as e enxugamentos. Em 2019, foram cerca de 67 mil ingressantes no ensino superior pelo Fies.<\/p>\n<p>Um dos principais motivos para as mudan\u00e7as nas regras do Fies, de acordo com gest\u00f5es anteriores do Minist\u00e9rio da Educa\u00e7\u00e3o, foi a alta inadimpl\u00eancia, ou seja, estudantes que contratam o financiamento e n\u00e3o quitam as d\u00edvidas ap\u00f3s formados.\u00a0<a href=\"https:\/\/agenciabrasil.ebc.com.br\/educacao\/noticia\/2021-07\/aumentos-de-mensalidade-nos-cursos-de-medicina-sobem-oito-vezes-para\" target=\"_blank\" rel=\"noopener\">O percentual de inadimpl\u00eancia<\/a>\u00a0registrado pelo programa chegou a atingir mais de 40%, de acordo com dados do minist\u00e9rio, de 2018.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<h6><strong>Ag\u00eancia Brasil<\/strong><\/h6>\n<hr \/>\n<p><strong><span style=\"color: #ff0000;\">By: miradouronot\u00edcias.com.br<\/span><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>UNE defende mudan\u00e7as no Fundo de Financiamento Estudantil Os recentes reajustes das mensalidades do ensino superior podem deixar v\u00e1rios estudantes de fora da faculdade, por n\u00e3o terem condi\u00e7\u00f5es de pagar, de acordo com estudo feito pela Quero Educa\u00e7\u00e3o. O levantamento mostra que enquanto os futuros alunos buscam mensalidades de cerca de R$ 500, a m\u00e9dia [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":15659,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23,26],"tags":[],"class_list":["post-15658","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque-5","category-educacao"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reajustes das mensalidades deixam estudantes sem op\u00e7\u00e3o - Miradouro Not\u00edcias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/miradouronoticias.com\/site\/2023\/06\/26\/reajustes-das-mensalidades-deixam-estudantes-sem-opcao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reajustes das mensalidades deixam estudantes sem op\u00e7\u00e3o - Miradouro Not\u00edcias\" \/>\n<meta property=\"og:description\" content=\"UNE defende mudan\u00e7as no Fundo de Financiamento Estudantil Os recentes reajustes das mensalidades do ensino superior podem deixar v\u00e1rios estudantes de fora da faculdade, por n\u00e3o terem condi\u00e7\u00f5es de pagar, de acordo com estudo feito pela Quero Educa\u00e7\u00e3o. O levantamento mostra que enquanto os futuros alunos buscam mensalidades de cerca de R$ 500, a m\u00e9dia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/miradouronoticias.com\/site\/2023\/06\/26\/reajustes-das-mensalidades-deixam-estudantes-sem-opcao\/\" \/>\n<meta property=\"og:site_name\" content=\"Miradouro Not\u00edcias\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-26T07:24:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2023\/06\/enem_vac_abr_2811214311.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cl\u00e1udia Olyver\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cl\u00e1udia Olyver\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2023\\\/06\\\/26\\\/reajustes-das-mensalidades-deixam-estudantes-sem-opcao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2023\\\/06\\\/26\\\/reajustes-das-mensalidades-deixam-estudantes-sem-opcao\\\/\"},\"author\":{\"name\":\"Cl\u00e1udia Olyver\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#\\\/schema\\\/person\\\/73440d8c82222950df86f3e1a16aad3b\"},\"headline\":\"Reajustes das mensalidades deixam estudantes sem op\u00e7\u00e3o\",\"datePublished\":\"2023-06-26T07:24:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2023\\\/06\\\/26\\\/reajustes-das-mensalidades-deixam-estudantes-sem-opcao\\\/\"},\"wordCount\":1304,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2023\\\/06\\\/26\\\/reajustes-das-mensalidades-deixam-estudantes-sem-opcao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/enem_vac_abr_2811214311.jpg\",\"articleSection\":[\"Destaque 5\",\"Educa\u00e7\u00e3o\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2023\\\/06\\\/26\\\/reajustes-das-mensalidades-deixam-estudantes-sem-opcao\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2023\\\/06\\\/26\\\/reajustes-das-mensalidades-deixam-estudantes-sem-opcao\\\/\",\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2023\\\/06\\\/26\\\/reajustes-das-mensalidades-deixam-estudantes-sem-opcao\\\/\",\"name\":\"Reajustes das mensalidades deixam estudantes sem op\u00e7\u00e3o - Miradouro Not\u00edcias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2023\\\/06\\\/26\\\/reajustes-das-mensalidades-deixam-estudantes-sem-opcao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2023\\\/06\\\/26\\\/reajustes-das-mensalidades-deixam-estudantes-sem-opcao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/enem_vac_abr_2811214311.jpg\",\"datePublished\":\"2023-06-26T07:24:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2023\\\/06\\\/26\\\/reajustes-das-mensalidades-deixam-estudantes-sem-opcao\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2023\\\/06\\\/26\\\/reajustes-das-mensalidades-deixam-estudantes-sem-opcao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2023\\\/06\\\/26\\\/reajustes-das-mensalidades-deixam-estudantes-sem-opcao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/enem_vac_abr_2811214311.jpg\",\"contentUrl\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/enem_vac_abr_2811214311.jpg\",\"width\":1170,\"height\":700,\"caption\":\"Participantes do Exame Nacional do Ensino M\u00e9dio (Enem) 2021 fazem, neste domingo (28), segundo dia de avalia\u00e7\u00e3o, provas de matem\u00e1tica e de ci\u00eancia da natureza.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2023\\\/06\\\/26\\\/reajustes-das-mensalidades-deixam-estudantes-sem-opcao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reajustes das mensalidades deixam estudantes sem op\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/\",\"name\":\"Miradouro Not\u00edcias\",\"description\":\"Informa\u00e7\u00f5es da cidade e regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#organization\",\"name\":\"Miradouro Not\u00edcias\",\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logomarcamiradouronoticias.png\",\"contentUrl\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logomarcamiradouronoticias.png\",\"width\":747,\"height\":263,\"caption\":\"Miradouro Not\u00edcias\"},\"image\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#\\\/schema\\\/person\\\/73440d8c82222950df86f3e1a16aad3b\",\"name\":\"Cl\u00e1udia Olyver\",\"sameAs\":[\"http:\\\/\\\/www.miradouronoticias.com\"],\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/author\\\/claudia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reajustes das mensalidades deixam estudantes sem op\u00e7\u00e3o - Miradouro Not\u00edcias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/miradouronoticias.com\/site\/2023\/06\/26\/reajustes-das-mensalidades-deixam-estudantes-sem-opcao\/","og_locale":"pt_BR","og_type":"article","og_title":"Reajustes das mensalidades deixam estudantes sem op\u00e7\u00e3o - Miradouro Not\u00edcias","og_description":"UNE defende mudan\u00e7as no Fundo de Financiamento Estudantil Os recentes reajustes das mensalidades do ensino superior podem deixar v\u00e1rios estudantes de fora da faculdade, por n\u00e3o terem condi\u00e7\u00f5es de pagar, de acordo com estudo feito pela Quero Educa\u00e7\u00e3o. O levantamento mostra que enquanto os futuros alunos buscam mensalidades de cerca de R$ 500, a m\u00e9dia [&hellip;]","og_url":"https:\/\/miradouronoticias.com\/site\/2023\/06\/26\/reajustes-das-mensalidades-deixam-estudantes-sem-opcao\/","og_site_name":"Miradouro Not\u00edcias","article_published_time":"2023-06-26T07:24:29+00:00","og_image":[{"width":1170,"height":700,"url":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2023\/06\/enem_vac_abr_2811214311.jpg","type":"image\/jpeg"}],"author":"Cl\u00e1udia Olyver","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Cl\u00e1udia Olyver","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/miradouronoticias.com\/site\/2023\/06\/26\/reajustes-das-mensalidades-deixam-estudantes-sem-opcao\/#article","isPartOf":{"@id":"https:\/\/miradouronoticias.com\/site\/2023\/06\/26\/reajustes-das-mensalidades-deixam-estudantes-sem-opcao\/"},"author":{"name":"Cl\u00e1udia Olyver","@id":"https:\/\/miradouronoticias.com\/site\/#\/schema\/person\/73440d8c82222950df86f3e1a16aad3b"},"headline":"Reajustes das mensalidades deixam estudantes sem op\u00e7\u00e3o","datePublished":"2023-06-26T07:24:29+00:00","mainEntityOfPage":{"@id":"https:\/\/miradouronoticias.com\/site\/2023\/06\/26\/reajustes-das-mensalidades-deixam-estudantes-sem-opcao\/"},"wordCount":1304,"commentCount":0,"publisher":{"@id":"https:\/\/miradouronoticias.com\/site\/#organization"},"image":{"@id":"https:\/\/miradouronoticias.com\/site\/2023\/06\/26\/reajustes-das-mensalidades-deixam-estudantes-sem-opcao\/#primaryimage"},"thumbnailUrl":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2023\/06\/enem_vac_abr_2811214311.jpg","articleSection":["Destaque 5","Educa\u00e7\u00e3o"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/miradouronoticias.com\/site\/2023\/06\/26\/reajustes-das-mensalidades-deixam-estudantes-sem-opcao\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/miradouronoticias.com\/site\/2023\/06\/26\/reajustes-das-mensalidades-deixam-estudantes-sem-opcao\/","url":"https:\/\/miradouronoticias.com\/site\/2023\/06\/26\/reajustes-das-mensalidades-deixam-estudantes-sem-opcao\/","name":"Reajustes das mensalidades deixam estudantes sem op\u00e7\u00e3o - Miradouro Not\u00edcias","isPartOf":{"@id":"https:\/\/miradouronoticias.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/miradouronoticias.com\/site\/2023\/06\/26\/reajustes-das-mensalidades-deixam-estudantes-sem-opcao\/#primaryimage"},"image":{"@id":"https:\/\/miradouronoticias.com\/site\/2023\/06\/26\/reajustes-das-mensalidades-deixam-estudantes-sem-opcao\/#primaryimage"},"thumbnailUrl":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2023\/06\/enem_vac_abr_2811214311.jpg","datePublished":"2023-06-26T07:24:29+00:00","breadcrumb":{"@id":"https:\/\/miradouronoticias.com\/site\/2023\/06\/26\/reajustes-das-mensalidades-deixam-estudantes-sem-opcao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/miradouronoticias.com\/site\/2023\/06\/26\/reajustes-das-mensalidades-deixam-estudantes-sem-opcao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/miradouronoticias.com\/site\/2023\/06\/26\/reajustes-das-mensalidades-deixam-estudantes-sem-opcao\/#primaryimage","url":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2023\/06\/enem_vac_abr_2811214311.jpg","contentUrl":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2023\/06\/enem_vac_abr_2811214311.jpg","width":1170,"height":700,"caption":"Participantes do Exame Nacional do Ensino M\u00e9dio (Enem) 2021 fazem, neste domingo (28), segundo dia de avalia\u00e7\u00e3o, provas de matem\u00e1tica e de ci\u00eancia da natureza."},{"@type":"BreadcrumbList","@id":"https:\/\/miradouronoticias.com\/site\/2023\/06\/26\/reajustes-das-mensalidades-deixam-estudantes-sem-opcao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/miradouronoticias.com\/site\/"},{"@type":"ListItem","position":2,"name":"Reajustes das mensalidades deixam estudantes sem op\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/miradouronoticias.com\/site\/#website","url":"https:\/\/miradouronoticias.com\/site\/","name":"Miradouro Not\u00edcias","description":"Informa\u00e7\u00f5es da cidade e regi\u00e3o","publisher":{"@id":"https:\/\/miradouronoticias.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/miradouronoticias.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/miradouronoticias.com\/site\/#organization","name":"Miradouro Not\u00edcias","url":"https:\/\/miradouronoticias.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/miradouronoticias.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2022\/01\/logomarcamiradouronoticias.png","contentUrl":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2022\/01\/logomarcamiradouronoticias.png","width":747,"height":263,"caption":"Miradouro Not\u00edcias"},"image":{"@id":"https:\/\/miradouronoticias.com\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/miradouronoticias.com\/site\/#\/schema\/person\/73440d8c82222950df86f3e1a16aad3b","name":"Cl\u00e1udia Olyver","sameAs":["http:\/\/www.miradouronoticias.com"],"url":"https:\/\/miradouronoticias.com\/site\/author\/claudia\/"}]}},"_links":{"self":[{"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/posts\/15658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/comments?post=15658"}],"version-history":[{"count":1,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/posts\/15658\/revisions"}],"predecessor-version":[{"id":15661,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/posts\/15658\/revisions\/15661"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/media\/15659"}],"wp:attachment":[{"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/media?parent=15658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/categories?post=15658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/tags?post=15658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}