{"id":14410,"date":"2023-04-19T11:03:37","date_gmt":"2023-04-19T14:03:37","guid":{"rendered":"https:\/\/miradouronoticias.com\/site\/?p=14410"},"modified":"2023-04-19T11:03:37","modified_gmt":"2023-04-19T14:03:37","slug":"educadores-dizem-que-novo-ensino-medio-amplia-desigualdades","status":"publish","type":"post","link":"https:\/\/miradouronoticias.com\/site\/2023\/04\/19\/educadores-dizem-que-novo-ensino-medio-amplia-desigualdades\/","title":{"rendered":"Educadores dizem que novo ensino m\u00e9dio amplia desigualdades"},"content":{"rendered":"<h3 class=\"col-10 offset-1 animated fadeInDown dealy-900 display-8 display-md-8 alt-font font-italic my-1 text-center\">Estudantes prometem ocupar ruas para pedir revoga\u00e7\u00e3o da reforma<\/h3>\n<div class=\"col-lg-12 mb-3\">\n<div class=\"row\">\n<div id=\"tts-container\" class=\"col-xl-7 offset-xl-1 col-lg-8 offset-lg-0 col-md-10 offset-md-1 mb-3\"><audio id=\"tts-player\" src=\"https:\/\/tts-app.ebc.com.br\/media\/tts\/202113.mp3\" controls=\"controls\" data-mce-fragment=\"1\"><\/audio><\/div>\n<\/div>\n<\/div>\n<div class=\"col-xl-7 offset-xl-1 col-lg-8 offset-lg-0 col-md-10 offset-md-1 mb-3\">\n<div class=\"post-item alt-font\">\n<div class=\"post-item-wrap\">\n<p>O novo ensino m\u00e9dio, que come\u00e7ou a ser implantado no pa\u00eds no ano passado, tem ampliado as desigualdades e prejudicado principalmente as pessoas mais pobres e vulner\u00e1veis. Para especialistas em educa\u00e7\u00e3o\u00a0ouvidos pela\u00a0<strong>Ag\u00eancia Brasil<\/strong>, a situa\u00e7\u00e3o tende a ser mais grave nas escolas p\u00fablicas.<\/p>\n<p>N\u00e3o s\u00e3o apenas educadores e especialistas que t\u00eam reclamado da reforma. Nesta quarta-feira (19), estudantes de todo o pa\u00eds prometem ocupar\u00a0as ruas para pedir que o Minist\u00e9rio da Educa\u00e7\u00e3o (MEC) revogue o novo sistema.<\/p>\n<p>Na semana passada, durante semin\u00e1rio realizado na Faculdade de Educa\u00e7\u00e3o da Universidade de S\u00e3o Paulo (USP), uma professora subiu ao palco para contar sua experi\u00eancia com o novo ensino m\u00e9dio. Formada em Ci\u00eancias Sociais, ela se viu obrigada, ap\u00f3s a lei de 2017 que mudou o ensino m\u00e9dio no pa\u00eds, a ter que ministrar oito diferentes itiner\u00e1rios formativos (conjunto de disciplinas, projetos, oficinas, n\u00facleos de estudo que os estudantes poder\u00e3o escolher no ensino m\u00e9dio).<\/p>\n<p>\u201cTenho 28 turmas do ensino m\u00e9dio e 34 aulas por semana. Essa \u00e9 a realidade hoje da reforma do ensino m\u00e9dio no estado de S\u00e3o Paulo\u201d, disse ela\u00a0durante o evento. \u201cO que temos observado \u00e9 que os alunos que est\u00e3o se formando n\u00e3o foram nem para o mercado de trabalho e nem para a universidade. Boa parte deles tem ido trabalhar como jovens aprendizes. Depois disso, tiveram que ir para outra \u00e1rea profissional\u201d, afirmou.<\/p>\n<p>Ela lembrou que S\u00e3o Paulo, por ser um dos primeiros estados a come\u00e7ar a implementa\u00e7\u00e3o do novo ensino m\u00e9dio, j\u00e1 tem observado algumas turmas se formando nessa nova metodologia. O\u00a0resultado que ela, como professora, tem vivenciado nas escolas, \u00e9 desesperador. \u201cO que eu vejo \u00e9 que esses alunos est\u00e3o se distanciando cada vez mais das universidades p\u00fablicas. O ch\u00e3o de f\u00e1brica na escola p\u00fablica est\u00e1 muito pior do que a gente imagina\u201d.<\/p>\n<p>&#8220;Temos uma reforma de ensino m\u00e9dio em curso que aumenta a desigualdade e produz desigualdades. E isso \u00e9 uma coisa grav\u00edssima&#8221;, disse Fernando C\u00e1ssio, doutor em Ci\u00eancias pela Universidade de S\u00e3o Paulo (USP) e professor da Universidade Federal do ABC (UFABC). Ele tamb\u00e9m integra a Rede Escola P\u00fablica e Universidade (Repu) e o comit\u00ea diretivo da Campanha Nacional pelo Direito \u00e0 Educa\u00e7\u00e3o.<\/p>\n<p>Segundo C\u00e1ssio, um dos elementos que torna essa reforma ainda mais desigual diz respeito \u00e0 aplica\u00e7\u00e3o dos itiner\u00e1rios formativos. Com problemas que v\u00e3o desde a m\u00e1 remunera\u00e7\u00e3o dos professores, passando por m\u00e1s condi\u00e7\u00f5es de trabalho, falta de concursos p\u00fablicos, problemas de infraestrutura e falta de investimentos e de forma\u00e7\u00e3o dos docentes, as escolas p\u00fablicas acabam sendo as mais prejudicadas com essa obriga\u00e7\u00e3o de implementa\u00e7\u00e3o dos itiner\u00e1rios formativos. Principalmente se essas escolas est\u00e3o localizadas em cidades menores ou em bairros\u00a0perif\u00e9ricos. \u201cOs mais vulner\u00e1veis s\u00e3o os mais prejudicados, sempre. Escola ind\u00edgena, quilombola, rural, de assentamento, EJA [educa\u00e7\u00e3o de jovens e adultos], Funda\u00e7\u00e3o Casa, classes penitenci\u00e1rias, regi\u00f5es pobres do estado e com baixo \u00cdndice de Desenvolvimento Humano [IDH]: todas elas s\u00e3o escolas com menos itiner\u00e1rios formativos \u00e0 escolha dos alunos\u201d, disse.<\/p>\n<p>A\u00a0professora de matem\u00e1tica\u00a0Elenira Vilela, que tamb\u00e9m \u00e9\u00a0coordenadora-geral do\u00a0Sindicato Nacional dos Servidores Federais da Educa\u00e7\u00e3o B\u00e1sica, Profissional e Tecnol\u00f3gica (Sinasefe),\u00a0concorda. Para ela, o novo ensino m\u00e9dio \u201caprofunda barbaramente as desigualdades\u201d.<\/p>\n<p>\u201cExiste o mito de que os jovens v\u00e3o poder escolher itiner\u00e1rios formativos dos quais eles sejam mais pr\u00f3ximos. Mas, na realidade, metade dos munic\u00edpios do Brasil tem uma \u00fanica escola de ensino m\u00e9dio que mal d\u00e1 conta de oferecer uma forma\u00e7\u00e3o padr\u00e3o para todo mundo. Ent\u00e3o, essas escolas n\u00e3o v\u00e3o conseguir ou n\u00e3o est\u00e3o conseguindo oferecer os diversos itiner\u00e1rios formativos\u201d.<\/p>\n<p>\u201cOs mais pobres n\u00e3o v\u00e3o ter acesso. Quem estuda em escolas particulares ou\u00a0federais, ou quem tem fam\u00edlia com mais condi\u00e7\u00f5es de acessar museus, escolas e viagens, vai\u00a0ter forma\u00e7\u00e3o mais ampla. Os mais pobres, os que vivem nas periferias e os que estudam em escolas do interior ter\u00e3o forma\u00e7\u00e3o mais restrita e piorada do que se tinha antes, de conhecimento geral. Al\u00e9m disso, n\u00e3o v\u00e3o fortalecer as possibilidades do mundo do trabalho como se tem propagado. Existem lugares, por exemplo, em que est\u00e3o sorteando qual o itiner\u00e1rio formativo que o estudante vai fazer. Isso n\u00e3o vai criar uma rela\u00e7\u00e3o melhor dele com o aprendizado\u201d, observou.<\/p>\n<p>A desigualdade tem se agravado porque a reforma determinou um teto m\u00e1ximo de horas para o chamado ensino proped\u00eautico, que visa\u00a0dar\u00a0uma\u00a0forma\u00e7\u00e3o geral e b\u00e1sica para que o aluno\u00a0possa\u00a0ingressar\u00a0em\u00a0curso superior.\u00a0Com isso,\u00a0horas que poderiam ser destinadas a\u00a0disciplinas consideradas essenciais como matem\u00e1tica, portugu\u00eas, hist\u00f3ria e geografia\u00a0est\u00e3o sendo retiradas para a aplica\u00e7\u00e3o dos\u00a0itiner\u00e1rios, que podem variar conforme a capacidade da escola.<\/p>\n<p>\u201cVoc\u00ea prop\u00f5e a cria\u00e7\u00e3o dos itiner\u00e1rios formativos como uma alternativa \u00e0 a\u00e7\u00e3o\u00a0proped\u00eautica.\u00a0Eles\u00a0criam\u00a0um limite para a forma\u00e7\u00e3o geral, o que acaba afastando mais os jovens, principalmente os mais pobres, da possibilidade de alcan\u00e7ar uma universidade. E, ao mesmo tempo, n\u00e3o oferece uma forma\u00e7\u00e3o para o trabalho que seja eficaz, de acordo com as demandas do mundo\u00a0do trabalho\u201d, disse Elenira.<\/p>\n<p>Para\u00a0esses\u00a0educadores e professores,\u00a0o que tem acontecido \u00e9 que\u00a0as escolas particulares n\u00e3o\u00a0est\u00e3o\u00a0cumprindo o\u00a0limite de horas para o ensino proped\u00eautico\u00a0e continuariam ministrando mais conte\u00fados\u00a0considerados essenciais\u00a0do que itiner\u00e1rios formativos. Com isso, seus alunos estariam mais preparados para vestibulares e o Exame Nacional do Ensino M\u00e9dio (Enem).<\/p>\n<p>Isso tem sido observado pelo professor F\u00e1bio Miguel, 43 anos, que d\u00e1 aulas tanto para o ensino m\u00e9dio privado quanto\u00a0para a\u00a0rede p\u00fablica estadual\u00a0da\u00a0cidade de Santo\u00a0Ant\u00f4nio\u00a0do Pinhal, no interior de S\u00e3o Paulo.\u00a0\u201cAcredito, sim, que [o novo ensino m\u00e9dio] vai aumentar as desigualdades. As particulares n\u00e3o est\u00e3o seguindo exatamente essa f\u00f3rmula que est\u00e1 na rede p\u00fablica, com essa quest\u00e3o dos itiner\u00e1rios, e que acabou retirando v\u00e1rias disciplinas como biologia, qu\u00edmica e boa parte das aulas de matem\u00e1tica e de l\u00edngua portuguesa\u201d, disse ele, em entrevista \u00e0<strong>\u00a0Ag\u00eancia Brasil<\/strong>. \u201cEu, por exemplo, trabalho com l\u00edngua portuguesa e literatura. Enquanto antes [da reforma do ensino m\u00e9dio] eu<\/p>\n<p>dava\u00a0cinco aulas, agora s\u00e3o somente duas. Ent\u00e3o, como trabalhar em duas aulas com conte\u00fado que era para cinco? Isso vai causar desigualdade n\u00e3o s\u00f3 para quando esse aluno for prestar o vestibular, mas tamb\u00e9m em sua vida profissional e, consequentemente, em sua vida acad\u00eamica\u201d, acrescentou.<\/p>\n<p>\u201cOs estudantes sabem que, na escola privada, n\u00e3o h\u00e1\u00a0nenhuma aula de\u00a0qu\u00edmica\u00a0a menos. Ningu\u00e9m substitui a aula de\u00a0qu\u00edmica\u00a0para aprender a fazer brigadeiro na escola privada.\u00a0Uma das fun\u00e7\u00f5es da escola deveria ser oferecer forma\u00e7\u00e3o s\u00f3lida.\u00a0E isso\u00a0ser\u00e1\u00a0a garantia da liberdade de escolha futura\u201d,\u00a0disse Fernando C\u00e1ssio.<\/p>\n<p>\u201cA primeira coisa que n\u00e3o funciona [nesse novo ensino m\u00e9dio] \u00e9 a ideia de flexibiliza\u00e7\u00e3o curricular, com supress\u00e3o de disciplinas. Voc\u00ea n\u00e3o melhora a qualidade da escola suprimindo conhecimento substantivo. Isso \u00e9 uma excresc\u00eancia. A escola deve\u00a0ser um lugar onde os estudantes t\u00eam\u00a0acesso ao conhecimento cient\u00edfico, \u00e0 cultura, \u00e0s ci\u00eancias humanas e naturais. Tem que ter isso. N\u00e3o \u00e9 poss\u00edvel, em primeiro lugar, voc\u00ea propor uma flexibiliza\u00e7\u00e3o curricular que vai substituir o conte\u00fado substantivo da escola por quinquilharia curricular. Isso n\u00e3o funciona, n\u00e3o vai funcionar, n\u00e3o tem como funcionar\u201d, afirmou.<\/p>\n<p>O presidente da Federa\u00e7\u00e3o Nacional das Escolas Particulares (Fenep), Bruno Eizerik, n\u00e3o concorda com a afirma\u00e7\u00e3o de que o novo ensino m\u00e9dio est\u00e1 ampliando as desigualdades no pa\u00eds. Para ele, as dificuldades encontradas pelas escolas p\u00fablicas na sua<\/p>\n<p>implementa\u00e7\u00e3o dizem mais respeito \u00e0 falta de gest\u00e3o. \u201cN\u00f3s temos um problema de gest\u00e3o na rede p\u00fablica. Se nosso aluno da escola privada custa menos e conseguimos fazer mais, \u00e9 porque alguma coisa est\u00e1 errada e isso diz respeito \u00e0 gest\u00e3o\u201d. \u201cO que acho \u00e9 que devemos melhorar as condi\u00e7\u00f5es f\u00edsicas da escola e implementar o novo ensino m\u00e9dio. N\u00e3o s\u00e3o coisas excludentes. Acho tamb\u00e9m que alguns estados est\u00e3o exagerando no n\u00famero de itiner\u00e1rios. E, \u00e0s vezes, pin\u00e7am o\u00a0exemplo de uma escola estadual que est\u00e1 ensinando a fazer brigadeiro. Mas, ao mesmo tempo, temos estados que est\u00e3o propondo no m\u00e1ximo quatro itiner\u00e1rios. E isso d\u00e1 para fazer. O que eu acho errado \u00e9 usar a desculpa de que a escola p\u00fablica n\u00e3o est\u00e1 pronta [para o novo ensino m\u00e9dio]: ela n\u00e3o est\u00e1 pronta nem para o antigo ensino m\u00e9dio\u201d, afirmou.<\/p>\n<p>Segundo Eizerik, o novo ensino m\u00e9dio est\u00e1 funcionando nas escolas privadas porque elas t\u00eam buscado oferecer poucos itiner\u00e1rios. \u201cO novo ensino m\u00e9dio \u00e9 dividido em duas partes: a primeira \u00e9 a base nacional curricular comum, que todos os alunos fazem. Aqui temos 1,8 mil horas, com quatro disciplinas que s\u00e3o obrigat\u00f3rias: portugu\u00eas, matem\u00e1tica, l\u00edngua inglesa e artes\u201d, explicou. \u201cTemos 1,2 mil horas de itiner\u00e1rios formativos, e a rede privada tem trabalhado com basicamente quatro itiner\u00e1rios: um para aqueles alunos que querem entrar na \u00e1rea da ci\u00eancia, outro para os que querem humanas, outro para a \u00e1rea da matem\u00e1tica e engenharias, e o \u00faltimo\u00a0para linguagens e letras. H\u00e1 um quinto caminho para quem quer fazer um curso t\u00e9cnico\u201d.<\/p>\n<h2>Teoria e pr\u00e1tica<\/h2>\n<p>Para Fernando C\u00e1ssio, o fato de o novo ensino m\u00e9dio ter sido aprovado a toque de caixa, sem ter sido discutido com a sociedade e, principalmente, com os atores da educa\u00e7\u00e3o, fez com que ele funcionasse apenas em teoria. \u201cNo fim das contas, o que vemos hoje no debate p\u00fablico \u00e9 uma tentativa de defender os valores da reforma, de dizer que essa reforma \u00e9 boa, que a ideia de flexibilizar o curr\u00edculo e dar liberdade \u00e9 boa. O problema \u00e9 que essas pessoas est\u00e3o falando em tese, em teoria. Mas essa reforma, com essa flexibiliza\u00e7\u00e3o, n\u00e3o est\u00e1 produzindo nenhum benef\u00edcio para os estudantes. Pelo contr\u00e1rio: a flexibiliza\u00e7\u00e3o destruiu a escola. N\u00e3o adianta a gente defender os valores abstratos de uma reforma que est\u00e1 objetiva e concretamente produzindo trag\u00e9dia\u201d, disse<\/p>\n<p>O presidente da Fenep contesta. Segundo ele, a reforma do ensino m\u00e9dio n\u00e3o aconteceu de uma hora para outra: ela vinha\u00a0sendo discutida no pa\u00eds desde a d\u00e9cada de 90. \u201cO \u00fanico pa\u00eds que tem uma escola \u00fanica do ensino m\u00e9dio \u00e9 o Brasil, onde todo mundo estuda a mesma coisa. E isso come\u00e7ou quando tivemos um regime de exce\u00e7\u00e3o n\u00e3o democr\u00e1tico. Se formos para a Argentina, o Chile, Uruguai, os Estados Unidos, o Canad\u00e1, a Europa e \u00c1sia, todos esses continentes e pa\u00edses, temos um ensino m\u00e9dio muito parecido com o que temos agora, com uma base geral e\u00a0itiner\u00e1rios para os alunos escolherem\u201d.<\/p>\n<p>Al\u00e9m de ter faltado transpar\u00eancia durante as discuss\u00f5es que precederam o novo ensino m\u00e9dio, faltou tamb\u00e9m informa\u00e7\u00e3o ap\u00f3s ele ter sido aprovado e se tornado lei, disse\u00a0o professor F\u00e1bio Miguel. Ele\u00a0reclama que os pais, alunos e o restante da comunidade n\u00e3o foram informados sobre como ele funcionaria. \u201cN\u00e3o foi passado claramente o que seria esse novo ensino m\u00e9dio\u201d.<\/p>\n<h2>Revoga\u00e7\u00e3o<\/h2>\n<p>Para Fernando C\u00e1ssio, a \u00fanica solu\u00e7\u00e3o poss\u00edvel para o novo ensino m\u00e9dio \u00e9 a sua revoga\u00e7\u00e3o imediata. &#8220;N\u00e3o acredito que a reforma do ensino m\u00e9dio seja reform\u00e1vel\u201d.<\/p>\n<p>Elenira tamb\u00e9m \u00e9 a favor da revoga\u00e7\u00e3o da reforma. \u201cA gente precisa revogar tudo o que estruturalmente foi colocado por essa reforma, que \u00e9 o teto m\u00e1ximo do ensino proped\u00eautico e a obrigatoriedade dos itiner\u00e1rios formativos\u201d, disse. \u201c\u00c9 \u00f3bvio que \u00e9 preciso\u00a0um processo de transi\u00e7\u00e3o para quem foi v\u00edtima dessa implanta\u00e7\u00e3o. H\u00e1\u00a0redes, como Santa Catarina e S\u00e3o Paulo, que j\u00e1 estavam fazendo antes. Ent\u00e3o, as v\u00edtimas desse processo t\u00eam que ser reparadas e ver como se recupera esse aprendizado. Daqui para a frente, temos que consertar esse erro grav\u00edssimo\u201d.<\/p>\n<p>O professor F\u00e1bio Miguel aponta falhas na reforma. Mas ele n\u00e3o tem certeza se a revoga\u00e7\u00e3o seria o melhor caminho. \u201cN\u00e3o acredito que ela precisaria ser totalmente revogada. A ideia \u00e9 boa. S\u00f3 que precisa, talvez, debat\u00ea-la mais, discuti-la mais. Essas manifesta\u00e7\u00f5es [que pedem a revoga\u00e7\u00e3o] s\u00e3o v\u00e1lidas porque mostram que as pessoas n\u00e3o est\u00e3o muito contentes com a ideia. O que eu sinto \u00e9 que boa parte dos alunos n\u00e3o est\u00e1 gostando\u201d.<\/p>\n<p>Para ele, uma das quest\u00f5es que precisaria ser proposta \u00e9 uma consulta preliminar aos alunos para que se conhe\u00e7a suas necessidades, que itiner\u00e1rios poderiam ser mais \u00fateis a eles. \u201cA ideia da mudan\u00e7a do novo ensino m\u00e9dio n\u00e3o \u00e9 ruim. Ela \u00e9 boa. Por\u00e9m, o que se deveria ser feito \u00e9 uma consulta aos alunos para saber, antes de abrir os itiner\u00e1rios, qual seria a op\u00e7\u00e3o deles, o que mais desejavam aprender. E s\u00f3 depois montar esse itiner\u00e1rio\u201d, disse.<\/p>\n<p>O\u00a0presidente da Fenep,\u00a0por sua vez,\u00a0\u00e9 contra a revoga\u00e7\u00e3o. \u201cExistem 13 institui\u00e7\u00f5es que t\u00eam defendido que a implementa\u00e7\u00e3o do ensino m\u00e9dio n\u00e3o deve parar. Primeiro, a Fenep. Em segundo, o colegiado de secret\u00e1rios estaduais de Educa\u00e7\u00e3o, que respondem pelas escolas p\u00fablicas. \u00c9 importante que n\u00e3o pare\u00e7a que, para a escola privada, est\u00e1 tudo bem e para a escola p\u00fablica n\u00e3o est\u00e1 tudo bem. Os secret\u00e1rios estaduais de\u00a0Educa\u00e7\u00e3o e os conselhos estaduais de\u00a0Educa\u00e7\u00e3o, que tratam das escolas p\u00fablicas, tamb\u00e9m entendem que o novo ensino m\u00e9dio deve continuar a ser\u00a0implementado&#8221;.<\/p>\n<p>\u201cN\u00e3o achamos que o novo ensino m\u00e9dio funcione \u00e0s mil maravilhas ou que est\u00e1 perfeito. N\u00f3s ainda estamos aprendendo com essa implementa\u00e7\u00e3o. E isso \u00e9 um processo. A gente precisa dar continuidade a esse processo e ver quais s\u00e3o os resultados\u201d, ponderou.<\/p>\n<p>Para Eizerik, o que poderia ser proposto para melhorar a reforma \u00e9 uma regulamenta\u00e7\u00e3o dos itiner\u00e1rios. \u201c\u00c9 muito complicado a gente pensar em sugest\u00f5es antes de terminar a pr\u00f3pria implementa\u00e7\u00e3o. Mas a cria\u00e7\u00e3o de poucos itiner\u00e1rios ajuda. E a\u00ed temos a quest\u00e3o que tem sido levantada: como ficam aquelas escolas do interior e que s\u00e3o \u00fanicas?\u00a0Podemos ter o que a gente chama de trilhas integradas, itiner\u00e1rios integrados, onde o aluno vai estudar um pouco de cada um. \u00c9 poss\u00edvel fazer v\u00e1rias constru\u00e7\u00f5es. E se a rede privada for chamado a opinar, estamos dispostos a sentar \u00e0\u00a0mesa\u201d.<\/p>\n<p>Com muitas reclama\u00e7\u00f5es direcionadas ao novo ensino m\u00e9dio, o Minist\u00e9rio da Educa\u00e7\u00e3o decidiu suspender o calend\u00e1rio de implanta\u00e7\u00e3o e propor a realiza\u00e7\u00e3o de uma consulta p\u00fablica para debater caminhos com a sociedade.<\/p>\n<p>Para o presidente da Fenep, essas audi\u00eancias p\u00fablicas podem ser produtivas se todos os atores puderem participar. \u201cEm primeiro lugar, preciso fazer uma cr\u00edtica. O ensino privado, que responde por 9 milh\u00f5es de alunos na educa\u00e7\u00e3o b\u00e1sica e 20% do total de alunos do pa\u00eds, n\u00e3o foi chamado para o grupo que vai estudar as modifica\u00e7\u00f5es que o governo pretende fazer\u201d. Quando o governo cria um grupo de trabalho e n\u00e3o chama a escola privada, esse grupo j\u00e1 come\u00e7a errado\u201d, observou.<\/p>\n<p>Fernando C\u00e1ssio, no entanto, acha as audi\u00eancias p\u00fablicas n\u00e3o v\u00e3o adiantar. Para ele, o ideal seria a realiza\u00e7\u00e3o de confer\u00eancias de\u00a0educa\u00e7\u00e3o que proponham novo modelo de ensino. \u201cO que defendo \u00e9 uma escola p\u00fablica que ofere\u00e7a forma\u00e7\u00e3o s\u00f3lida para os estudantes como ideia geral. Acho que isso pode ser constru\u00eddo. N\u00e3o vejo a revoga\u00e7\u00e3o da reforma do ensino m\u00e9dio como \u00faltimo passo, vejo\u00a0como passo inicial. Ela precisa ser revogada imediatamente porque precisamos disparar um processo nacional de constru\u00e7\u00e3o de uma pol\u00edtica educacional para o ensino m\u00e9dio que tenha o m\u00ednimo de consenso. Precisamos, por exemplo, fazer uma Confer\u00eancia Nacional de Educa\u00e7\u00e3o para discutir o ensino m\u00e9dio. A\u00ed sim, as posi\u00e7\u00f5es em disputa v\u00e3o entrar na arena e vamos ter uma pol\u00edtica p\u00fablica que vai refletir anseios, expectativas e concep\u00e7\u00f5es de educa\u00e7\u00e3o de uma sociedade mais ampla &#8211; e n\u00e3o de meia duzia de atores privados, como vem acontecendo\u201d, disse.<\/p>\n<p>\u201cA quest\u00e3o de ser uma confer\u00eancia \u00e9 porque semin\u00e1rio n\u00e3o \u00e9 um processo deliberativo. Semin\u00e1rio a gente senta, conversa, cada um fala o que pensa e n\u00e3o tem f\u00f3rmula de sistematiza\u00e7\u00e3o. Confer\u00eancia voc\u00ea tem formas deliberativas e chega ao final com um documento elaborado pela sociedade brasileira, dizendo o que quer\u00a0para o ensino m\u00e9dio. O que a gente quer \u00e9 um espa\u00e7o deliberativo, n\u00e3o s\u00f3 consultivo\u201d, acrescentou Elenira.<\/p>\n<p>Para ela, um dos modelos que funcionam no pa\u00eds e que poderia ser levado em conta na constru\u00e7\u00e3o de um novo ensino m\u00e9dio seria o adotado pelos institutos federais. \u201cNa rede em que atuo, que \u00e9 a dos institutos federais, fazemos um ensino m\u00e9dio t\u00e9cnico integrando muito bem o que chamamos de conhecimento proped\u00eautico com o mundo do trabalho, com forma\u00e7\u00e3o profissional que realmente habilita o estudante para o trabalho, al\u00e9m de desenvolver capacidade cr\u00edtica na rela\u00e7\u00e3o com a cultura e a sociedade\u201d.<\/p>\n<p>\u201cA principal cr\u00edtica a esse modelo \u00e9 que ele seria muito mais caro, ent\u00e3o, n\u00e3o poderia ser a refer\u00eancia. De fato, \u00e9 um modelo mais caro porque temos professores e trabalhadoras da educa\u00e7\u00e3o em geral muito mais formados, com sal\u00e1rios bons, com condi\u00e7\u00f5es de trabalho e que fazem pesquisa e extens\u00e3o de maneira articulada. Mas a\u00ed h\u00e1 coisas que temos que nos questionar como pa\u00eds: a gente quer um pa\u00eds que tenha educa\u00e7\u00e3o de ponta e que realmente possa impulsionar o desenvolvimento dos nossos jovens e o desenvolvimento t\u00e9cnico e cient\u00edfico brasileiro? Se queremos, precisamos\u00a0fazer um brutal investimento em educa\u00e7\u00e3o\u201d.<\/p>\n<p>Procurado pela\u00a0<strong>Ag\u00eancia Brasil<\/strong>, o MEC\u00a0informou que n\u00e3o vai emitir opini\u00e3o sobre as manifesta\u00e7\u00f5es que pedem ou n\u00e3o a revoga\u00e7\u00e3o do novo ensino m\u00e9dio. A pasta disse que \u201ctodos os atores do Minist\u00e9rio da Educa\u00e7\u00e3o e entidades que conduzem a consulta p\u00fablica est\u00e3o trabalhando coletivamente na constru\u00e7\u00e3o dessa agenda\u201d.<\/p>\n<p>Segundo o minist\u00e9rio, \u201cos detalhamentos dos instrumentos ser\u00e3o tornados p\u00fablicos assim que conclu\u00eddos&#8221;.<\/p>\n<h6><strong style=\"font-family: Roboto, sans-serif;\">Ag\u00eancia Brasil<\/strong><\/h6>\n<\/div>\n<\/div>\n<\/div>\n<hr \/>\n<p><strong><span style=\"color: #ff0000;\">By: miradouronot\u00edcias.com.br<\/span><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estudantes prometem ocupar ruas para pedir revoga\u00e7\u00e3o da reforma O novo ensino m\u00e9dio, que come\u00e7ou a ser implantado no pa\u00eds no ano passado, tem ampliado as desigualdades e prejudicado principalmente as pessoas mais pobres e vulner\u00e1veis. Para especialistas em educa\u00e7\u00e3o\u00a0ouvidos pela\u00a0Ag\u00eancia Brasil, a situa\u00e7\u00e3o tende a ser mais grave nas escolas p\u00fablicas. N\u00e3o s\u00e3o apenas [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":14411,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,26],"tags":[],"class_list":["post-14410","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque-3","category-educacao"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Educadores dizem que novo ensino m\u00e9dio amplia desigualdades - Miradouro Not\u00edcias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/miradouronoticias.com\/site\/2023\/04\/19\/educadores-dizem-que-novo-ensino-medio-amplia-desigualdades\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Educadores dizem que novo ensino m\u00e9dio amplia desigualdades - Miradouro Not\u00edcias\" \/>\n<meta property=\"og:description\" content=\"Estudantes prometem ocupar ruas para pedir revoga\u00e7\u00e3o da reforma O novo ensino m\u00e9dio, que come\u00e7ou a ser implantado no pa\u00eds no ano passado, tem ampliado as desigualdades e prejudicado principalmente as pessoas mais pobres e vulner\u00e1veis. Para especialistas em educa\u00e7\u00e3o\u00a0ouvidos pela\u00a0Ag\u00eancia Brasil, a situa\u00e7\u00e3o tende a ser mais grave nas escolas p\u00fablicas. N\u00e3o s\u00e3o apenas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/miradouronoticias.com\/site\/2023\/04\/19\/educadores-dizem-que-novo-ensino-medio-amplia-desigualdades\/\" \/>\n<meta property=\"og:site_name\" content=\"Miradouro Not\u00edcias\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-19T14:03:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2023\/04\/img_20230315_112709.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cl\u00e1udia Olyver\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cl\u00e1udia Olyver\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"16 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2023\\\/04\\\/19\\\/educadores-dizem-que-novo-ensino-medio-amplia-desigualdades\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2023\\\/04\\\/19\\\/educadores-dizem-que-novo-ensino-medio-amplia-desigualdades\\\/\"},\"author\":{\"name\":\"Cl\u00e1udia Olyver\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#\\\/schema\\\/person\\\/73440d8c82222950df86f3e1a16aad3b\"},\"headline\":\"Educadores dizem que novo ensino m\u00e9dio amplia desigualdades\",\"datePublished\":\"2023-04-19T14:03:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2023\\\/04\\\/19\\\/educadores-dizem-que-novo-ensino-medio-amplia-desigualdades\\\/\"},\"wordCount\":3264,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2023\\\/04\\\/19\\\/educadores-dizem-que-novo-ensino-medio-amplia-desigualdades\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/img_20230315_112709.jpg\",\"articleSection\":[\"Destaque 3\",\"Educa\u00e7\u00e3o\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2023\\\/04\\\/19\\\/educadores-dizem-que-novo-ensino-medio-amplia-desigualdades\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2023\\\/04\\\/19\\\/educadores-dizem-que-novo-ensino-medio-amplia-desigualdades\\\/\",\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2023\\\/04\\\/19\\\/educadores-dizem-que-novo-ensino-medio-amplia-desigualdades\\\/\",\"name\":\"Educadores dizem que novo ensino m\u00e9dio amplia desigualdades - Miradouro Not\u00edcias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2023\\\/04\\\/19\\\/educadores-dizem-que-novo-ensino-medio-amplia-desigualdades\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2023\\\/04\\\/19\\\/educadores-dizem-que-novo-ensino-medio-amplia-desigualdades\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/img_20230315_112709.jpg\",\"datePublished\":\"2023-04-19T14:03:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2023\\\/04\\\/19\\\/educadores-dizem-que-novo-ensino-medio-amplia-desigualdades\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2023\\\/04\\\/19\\\/educadores-dizem-que-novo-ensino-medio-amplia-desigualdades\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2023\\\/04\\\/19\\\/educadores-dizem-que-novo-ensino-medio-amplia-desigualdades\\\/#primaryimage\",\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/img_20230315_112709.jpg\",\"contentUrl\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/img_20230315_112709.jpg\",\"width\":1170,\"height\":700,\"caption\":\"S\u00e3o Paulo (SP), 15\\\/03\\\/2023 - Estudantes secundaristas protestam nas ruas pedindo a revoga\u00e7\u00e3o do Novo Ensino M\u00e9dio. Foto: Fernando Fraz\u00e3o\\\/Ag\u00eancia Brasil\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2023\\\/04\\\/19\\\/educadores-dizem-que-novo-ensino-medio-amplia-desigualdades\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Educadores dizem que novo ensino m\u00e9dio amplia desigualdades\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/\",\"name\":\"Miradouro Not\u00edcias\",\"description\":\"Informa\u00e7\u00f5es da cidade e regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#organization\",\"name\":\"Miradouro Not\u00edcias\",\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logomarcamiradouronoticias.png\",\"contentUrl\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logomarcamiradouronoticias.png\",\"width\":747,\"height\":263,\"caption\":\"Miradouro Not\u00edcias\"},\"image\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#\\\/schema\\\/person\\\/73440d8c82222950df86f3e1a16aad3b\",\"name\":\"Cl\u00e1udia Olyver\",\"sameAs\":[\"http:\\\/\\\/www.miradouronoticias.com\"],\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/author\\\/claudia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Educadores dizem que novo ensino m\u00e9dio amplia desigualdades - Miradouro Not\u00edcias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/miradouronoticias.com\/site\/2023\/04\/19\/educadores-dizem-que-novo-ensino-medio-amplia-desigualdades\/","og_locale":"pt_BR","og_type":"article","og_title":"Educadores dizem que novo ensino m\u00e9dio amplia desigualdades - Miradouro Not\u00edcias","og_description":"Estudantes prometem ocupar ruas para pedir revoga\u00e7\u00e3o da reforma O novo ensino m\u00e9dio, que come\u00e7ou a ser implantado no pa\u00eds no ano passado, tem ampliado as desigualdades e prejudicado principalmente as pessoas mais pobres e vulner\u00e1veis. Para especialistas em educa\u00e7\u00e3o\u00a0ouvidos pela\u00a0Ag\u00eancia Brasil, a situa\u00e7\u00e3o tende a ser mais grave nas escolas p\u00fablicas. N\u00e3o s\u00e3o apenas [&hellip;]","og_url":"https:\/\/miradouronoticias.com\/site\/2023\/04\/19\/educadores-dizem-que-novo-ensino-medio-amplia-desigualdades\/","og_site_name":"Miradouro Not\u00edcias","article_published_time":"2023-04-19T14:03:37+00:00","og_image":[{"width":1170,"height":700,"url":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2023\/04\/img_20230315_112709.jpg","type":"image\/jpeg"}],"author":"Cl\u00e1udia Olyver","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Cl\u00e1udia Olyver","Est. tempo de leitura":"16 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/miradouronoticias.com\/site\/2023\/04\/19\/educadores-dizem-que-novo-ensino-medio-amplia-desigualdades\/#article","isPartOf":{"@id":"https:\/\/miradouronoticias.com\/site\/2023\/04\/19\/educadores-dizem-que-novo-ensino-medio-amplia-desigualdades\/"},"author":{"name":"Cl\u00e1udia Olyver","@id":"https:\/\/miradouronoticias.com\/site\/#\/schema\/person\/73440d8c82222950df86f3e1a16aad3b"},"headline":"Educadores dizem que novo ensino m\u00e9dio amplia desigualdades","datePublished":"2023-04-19T14:03:37+00:00","mainEntityOfPage":{"@id":"https:\/\/miradouronoticias.com\/site\/2023\/04\/19\/educadores-dizem-que-novo-ensino-medio-amplia-desigualdades\/"},"wordCount":3264,"commentCount":0,"publisher":{"@id":"https:\/\/miradouronoticias.com\/site\/#organization"},"image":{"@id":"https:\/\/miradouronoticias.com\/site\/2023\/04\/19\/educadores-dizem-que-novo-ensino-medio-amplia-desigualdades\/#primaryimage"},"thumbnailUrl":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2023\/04\/img_20230315_112709.jpg","articleSection":["Destaque 3","Educa\u00e7\u00e3o"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/miradouronoticias.com\/site\/2023\/04\/19\/educadores-dizem-que-novo-ensino-medio-amplia-desigualdades\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/miradouronoticias.com\/site\/2023\/04\/19\/educadores-dizem-que-novo-ensino-medio-amplia-desigualdades\/","url":"https:\/\/miradouronoticias.com\/site\/2023\/04\/19\/educadores-dizem-que-novo-ensino-medio-amplia-desigualdades\/","name":"Educadores dizem que novo ensino m\u00e9dio amplia desigualdades - Miradouro Not\u00edcias","isPartOf":{"@id":"https:\/\/miradouronoticias.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/miradouronoticias.com\/site\/2023\/04\/19\/educadores-dizem-que-novo-ensino-medio-amplia-desigualdades\/#primaryimage"},"image":{"@id":"https:\/\/miradouronoticias.com\/site\/2023\/04\/19\/educadores-dizem-que-novo-ensino-medio-amplia-desigualdades\/#primaryimage"},"thumbnailUrl":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2023\/04\/img_20230315_112709.jpg","datePublished":"2023-04-19T14:03:37+00:00","breadcrumb":{"@id":"https:\/\/miradouronoticias.com\/site\/2023\/04\/19\/educadores-dizem-que-novo-ensino-medio-amplia-desigualdades\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/miradouronoticias.com\/site\/2023\/04\/19\/educadores-dizem-que-novo-ensino-medio-amplia-desigualdades\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/miradouronoticias.com\/site\/2023\/04\/19\/educadores-dizem-que-novo-ensino-medio-amplia-desigualdades\/#primaryimage","url":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2023\/04\/img_20230315_112709.jpg","contentUrl":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2023\/04\/img_20230315_112709.jpg","width":1170,"height":700,"caption":"S\u00e3o Paulo (SP), 15\/03\/2023 - Estudantes secundaristas protestam nas ruas pedindo a revoga\u00e7\u00e3o do Novo Ensino M\u00e9dio. Foto: Fernando Fraz\u00e3o\/Ag\u00eancia Brasil"},{"@type":"BreadcrumbList","@id":"https:\/\/miradouronoticias.com\/site\/2023\/04\/19\/educadores-dizem-que-novo-ensino-medio-amplia-desigualdades\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/miradouronoticias.com\/site\/"},{"@type":"ListItem","position":2,"name":"Educadores dizem que novo ensino m\u00e9dio amplia desigualdades"}]},{"@type":"WebSite","@id":"https:\/\/miradouronoticias.com\/site\/#website","url":"https:\/\/miradouronoticias.com\/site\/","name":"Miradouro Not\u00edcias","description":"Informa\u00e7\u00f5es da cidade e regi\u00e3o","publisher":{"@id":"https:\/\/miradouronoticias.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/miradouronoticias.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/miradouronoticias.com\/site\/#organization","name":"Miradouro Not\u00edcias","url":"https:\/\/miradouronoticias.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/miradouronoticias.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2022\/01\/logomarcamiradouronoticias.png","contentUrl":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2022\/01\/logomarcamiradouronoticias.png","width":747,"height":263,"caption":"Miradouro Not\u00edcias"},"image":{"@id":"https:\/\/miradouronoticias.com\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/miradouronoticias.com\/site\/#\/schema\/person\/73440d8c82222950df86f3e1a16aad3b","name":"Cl\u00e1udia Olyver","sameAs":["http:\/\/www.miradouronoticias.com"],"url":"https:\/\/miradouronoticias.com\/site\/author\/claudia\/"}]}},"_links":{"self":[{"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/posts\/14410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/comments?post=14410"}],"version-history":[{"count":2,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/posts\/14410\/revisions"}],"predecessor-version":[{"id":14413,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/posts\/14410\/revisions\/14413"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/media\/14411"}],"wp:attachment":[{"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/media?parent=14410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/categories?post=14410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/tags?post=14410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}