{"id":10182,"date":"2022-10-19T18:07:58","date_gmt":"2022-10-19T21:07:58","guid":{"rendered":"https:\/\/miradouronoticias.com\/site\/?p=10182"},"modified":"2022-10-19T18:07:58","modified_gmt":"2022-10-19T21:07:58","slug":"prf-apreende-50-mil-macos-de-cigarros-contrabandeados-dentro-de-caminhao-em-tres-marias-mg","status":"publish","type":"post","link":"https:\/\/miradouronoticias.com\/site\/2022\/10\/19\/prf-apreende-50-mil-macos-de-cigarros-contrabandeados-dentro-de-caminhao-em-tres-marias-mg\/","title":{"rendered":"PRF apreende 50 mil ma\u00e7os de cigarros contrabandeados dentro de caminh\u00e3o, em Tr\u00eas Marias (MG)"},"content":{"rendered":"<p>CIGARROS, CONTRABANDO<\/p>\n<h2>Apreens\u00e3o gerou preju\u00edzo de R$ 250 mil aos contrabandistas<\/h2>\n<div id=\"content-core\">\n<div id=\"parent-fieldname-text\" class=\"\">\n<div>\n<p class=\"western\" align=\"justify\">APol\u00edcia Rodovi\u00e1ria Federal (PRF) apreendeu um caminh\u00e3o carregado de cigarros durante uma opera\u00e7\u00e3o de combate ao crime, na\u00a0tarde\u00a0de ter\u00e7a-feira (18\/10). Ao todo, foram apreendidos\u00a050 mil ma\u00e7os de cigarros contrabandeados, no Km\u00a0284\u00a0da BR\u00a0040, em\u00a0Tr\u00eas Marias\u00a0(MG).<\/p>\n<p class=\"western\" align=\"justify\">A apreens\u00e3o ocorreu durante a abordagem de um caminh\u00e3o ba\u00fa, ap\u00f3s os policiais localizarem 100 caixas de cigarro contrabandeados, da marca Gift box, sem documenta\u00e7\u00e3o fiscal.<\/p>\n<p class=\"western\" align=\"justify\">Realizada a verifica\u00e7\u00e3o da carga, foi constatada a exist\u00eancia de 50 mil ma\u00e7os de cigarros. A carga est\u00e1 avaliada aproximadamente em R$ 250 mil reais.<\/p>\n<p class=\"western\" align=\"justify\">O condutor informou que saiu de Belo Horizonte (MG) com destino a cidade de Paracatu (MG).<\/p>\n<p class=\"western\" align=\"justify\">Diante dos fatos e considerando a prov\u00e1vel ocorr\u00eancia do crime de contrabando, foi dada voz de pris\u00e3o ao envolvido que foi informado de seus direitos constitucionais e conduzido ileso para a PF de Belo Horizonte(MG). O caminh\u00e3o e a carga de cigarros contrabandeados est\u00e3o \u00e0 disposi\u00e7\u00e3o da Receita Federal.<\/p>\n<p class=\"western\" align=\"justify\"><img decoding=\"async\" class=\"image-inline\" src=\"https:\/\/www.gov.br\/prf\/pt-br\/noticias\/estaduais\/minas-gerais\/2022\/outubro\/prf-apreende-50-mil-macos-de-cigarros-contrabandeados-dentro-de-caminhao-em-tres-marias-mg\/CigarrosTrsMarias2.jpeg\" alt=\"\" \/><\/p>\n<\/div>\n<\/div>\n<\/div>\n<h6><strong>Fonte: PRF<\/strong><\/h6>\n<hr \/>\n<p><strong><span style=\"color: #ff0000;\">By: miradouronot\u00edcias.com.br<\/span><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CIGARROS, CONTRABANDO Apreens\u00e3o gerou preju\u00edzo de R$ 250 mil aos contrabandistas APol\u00edcia Rodovi\u00e1ria Federal (PRF) apreendeu um caminh\u00e3o carregado de cigarros durante uma opera\u00e7\u00e3o de combate ao crime, na\u00a0tarde\u00a0de ter\u00e7a-feira (18\/10). Ao todo, foram apreendidos\u00a050 mil ma\u00e7os de cigarros contrabandeados, no Km\u00a0284\u00a0da BR\u00a0040, em\u00a0Tr\u00eas Marias\u00a0(MG). A apreens\u00e3o ocorreu durante a abordagem de um caminh\u00e3o ba\u00fa, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":10184,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,18],"tags":[51],"class_list":["post-10182","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque-1","category-policia","tag-cigarros-contrabando"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PRF apreende 50 mil ma\u00e7os de cigarros contrabandeados dentro de caminh\u00e3o, em Tr\u00eas Marias (MG) - Miradouro Not\u00edcias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/miradouronoticias.com\/site\/2022\/10\/19\/prf-apreende-50-mil-macos-de-cigarros-contrabandeados-dentro-de-caminhao-em-tres-marias-mg\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PRF apreende 50 mil ma\u00e7os de cigarros contrabandeados dentro de caminh\u00e3o, em Tr\u00eas Marias (MG) - Miradouro Not\u00edcias\" \/>\n<meta property=\"og:description\" content=\"CIGARROS, CONTRABANDO Apreens\u00e3o gerou preju\u00edzo de R$ 250 mil aos contrabandistas APol\u00edcia Rodovi\u00e1ria Federal (PRF) apreendeu um caminh\u00e3o carregado de cigarros durante uma opera\u00e7\u00e3o de combate ao crime, na\u00a0tarde\u00a0de ter\u00e7a-feira (18\/10). Ao todo, foram apreendidos\u00a050 mil ma\u00e7os de cigarros contrabandeados, no Km\u00a0284\u00a0da BR\u00a0040, em\u00a0Tr\u00eas Marias\u00a0(MG). A apreens\u00e3o ocorreu durante a abordagem de um caminh\u00e3o ba\u00fa, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/miradouronoticias.com\/site\/2022\/10\/19\/prf-apreende-50-mil-macos-de-cigarros-contrabandeados-dentro-de-caminhao-em-tres-marias-mg\/\" \/>\n<meta property=\"og:site_name\" content=\"Miradouro Not\u00edcias\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-19T21:07:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2022\/10\/29db2a9d-3961-4352-823a-ac1c47e99972.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cl\u00e1udia Olyver\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cl\u00e1udia Olyver\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2022\\\/10\\\/19\\\/prf-apreende-50-mil-macos-de-cigarros-contrabandeados-dentro-de-caminhao-em-tres-marias-mg\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2022\\\/10\\\/19\\\/prf-apreende-50-mil-macos-de-cigarros-contrabandeados-dentro-de-caminhao-em-tres-marias-mg\\\/\"},\"author\":{\"name\":\"Cl\u00e1udia Olyver\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#\\\/schema\\\/person\\\/73440d8c82222950df86f3e1a16aad3b\"},\"headline\":\"PRF apreende 50 mil ma\u00e7os de cigarros contrabandeados dentro de caminh\u00e3o, em Tr\u00eas Marias (MG)\",\"datePublished\":\"2022-10-19T21:07:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2022\\\/10\\\/19\\\/prf-apreende-50-mil-macos-de-cigarros-contrabandeados-dentro-de-caminhao-em-tres-marias-mg\\\/\"},\"wordCount\":207,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2022\\\/10\\\/19\\\/prf-apreende-50-mil-macos-de-cigarros-contrabandeados-dentro-de-caminhao-em-tres-marias-mg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/29db2a9d-3961-4352-823a-ac1c47e99972.jpeg\",\"keywords\":[\"CIGARROS CONTRABANDO\"],\"articleSection\":[\"Destaque 1\",\"Pol\u00edcia\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2022\\\/10\\\/19\\\/prf-apreende-50-mil-macos-de-cigarros-contrabandeados-dentro-de-caminhao-em-tres-marias-mg\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2022\\\/10\\\/19\\\/prf-apreende-50-mil-macos-de-cigarros-contrabandeados-dentro-de-caminhao-em-tres-marias-mg\\\/\",\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2022\\\/10\\\/19\\\/prf-apreende-50-mil-macos-de-cigarros-contrabandeados-dentro-de-caminhao-em-tres-marias-mg\\\/\",\"name\":\"PRF apreende 50 mil ma\u00e7os de cigarros contrabandeados dentro de caminh\u00e3o, em Tr\u00eas Marias (MG) - Miradouro Not\u00edcias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2022\\\/10\\\/19\\\/prf-apreende-50-mil-macos-de-cigarros-contrabandeados-dentro-de-caminhao-em-tres-marias-mg\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2022\\\/10\\\/19\\\/prf-apreende-50-mil-macos-de-cigarros-contrabandeados-dentro-de-caminhao-em-tres-marias-mg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/29db2a9d-3961-4352-823a-ac1c47e99972.jpeg\",\"datePublished\":\"2022-10-19T21:07:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2022\\\/10\\\/19\\\/prf-apreende-50-mil-macos-de-cigarros-contrabandeados-dentro-de-caminhao-em-tres-marias-mg\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2022\\\/10\\\/19\\\/prf-apreende-50-mil-macos-de-cigarros-contrabandeados-dentro-de-caminhao-em-tres-marias-mg\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2022\\\/10\\\/19\\\/prf-apreende-50-mil-macos-de-cigarros-contrabandeados-dentro-de-caminhao-em-tres-marias-mg\\\/#primaryimage\",\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/29db2a9d-3961-4352-823a-ac1c47e99972.jpeg\",\"contentUrl\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/29db2a9d-3961-4352-823a-ac1c47e99972.jpeg\",\"width\":768,\"height\":576},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/2022\\\/10\\\/19\\\/prf-apreende-50-mil-macos-de-cigarros-contrabandeados-dentro-de-caminhao-em-tres-marias-mg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PRF apreende 50 mil ma\u00e7os de cigarros contrabandeados dentro de caminh\u00e3o, em Tr\u00eas Marias (MG)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/\",\"name\":\"Miradouro Not\u00edcias\",\"description\":\"Informa\u00e7\u00f5es da cidade e regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#organization\",\"name\":\"Miradouro Not\u00edcias\",\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logomarcamiradouronoticias.png\",\"contentUrl\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logomarcamiradouronoticias.png\",\"width\":747,\"height\":263,\"caption\":\"Miradouro Not\u00edcias\"},\"image\":{\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/#\\\/schema\\\/person\\\/73440d8c82222950df86f3e1a16aad3b\",\"name\":\"Cl\u00e1udia Olyver\",\"sameAs\":[\"http:\\\/\\\/www.miradouronoticias.com\"],\"url\":\"https:\\\/\\\/miradouronoticias.com\\\/site\\\/author\\\/claudia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PRF apreende 50 mil ma\u00e7os de cigarros contrabandeados dentro de caminh\u00e3o, em Tr\u00eas Marias (MG) - Miradouro Not\u00edcias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/miradouronoticias.com\/site\/2022\/10\/19\/prf-apreende-50-mil-macos-de-cigarros-contrabandeados-dentro-de-caminhao-em-tres-marias-mg\/","og_locale":"pt_BR","og_type":"article","og_title":"PRF apreende 50 mil ma\u00e7os de cigarros contrabandeados dentro de caminh\u00e3o, em Tr\u00eas Marias (MG) - Miradouro Not\u00edcias","og_description":"CIGARROS, CONTRABANDO Apreens\u00e3o gerou preju\u00edzo de R$ 250 mil aos contrabandistas APol\u00edcia Rodovi\u00e1ria Federal (PRF) apreendeu um caminh\u00e3o carregado de cigarros durante uma opera\u00e7\u00e3o de combate ao crime, na\u00a0tarde\u00a0de ter\u00e7a-feira (18\/10). Ao todo, foram apreendidos\u00a050 mil ma\u00e7os de cigarros contrabandeados, no Km\u00a0284\u00a0da BR\u00a0040, em\u00a0Tr\u00eas Marias\u00a0(MG). A apreens\u00e3o ocorreu durante a abordagem de um caminh\u00e3o ba\u00fa, [&hellip;]","og_url":"https:\/\/miradouronoticias.com\/site\/2022\/10\/19\/prf-apreende-50-mil-macos-de-cigarros-contrabandeados-dentro-de-caminhao-em-tres-marias-mg\/","og_site_name":"Miradouro Not\u00edcias","article_published_time":"2022-10-19T21:07:58+00:00","og_image":[{"width":768,"height":576,"url":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2022\/10\/29db2a9d-3961-4352-823a-ac1c47e99972.jpeg","type":"image\/jpeg"}],"author":"Cl\u00e1udia Olyver","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Cl\u00e1udia Olyver","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/miradouronoticias.com\/site\/2022\/10\/19\/prf-apreende-50-mil-macos-de-cigarros-contrabandeados-dentro-de-caminhao-em-tres-marias-mg\/#article","isPartOf":{"@id":"https:\/\/miradouronoticias.com\/site\/2022\/10\/19\/prf-apreende-50-mil-macos-de-cigarros-contrabandeados-dentro-de-caminhao-em-tres-marias-mg\/"},"author":{"name":"Cl\u00e1udia Olyver","@id":"https:\/\/miradouronoticias.com\/site\/#\/schema\/person\/73440d8c82222950df86f3e1a16aad3b"},"headline":"PRF apreende 50 mil ma\u00e7os de cigarros contrabandeados dentro de caminh\u00e3o, em Tr\u00eas Marias (MG)","datePublished":"2022-10-19T21:07:58+00:00","mainEntityOfPage":{"@id":"https:\/\/miradouronoticias.com\/site\/2022\/10\/19\/prf-apreende-50-mil-macos-de-cigarros-contrabandeados-dentro-de-caminhao-em-tres-marias-mg\/"},"wordCount":207,"commentCount":0,"publisher":{"@id":"https:\/\/miradouronoticias.com\/site\/#organization"},"image":{"@id":"https:\/\/miradouronoticias.com\/site\/2022\/10\/19\/prf-apreende-50-mil-macos-de-cigarros-contrabandeados-dentro-de-caminhao-em-tres-marias-mg\/#primaryimage"},"thumbnailUrl":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2022\/10\/29db2a9d-3961-4352-823a-ac1c47e99972.jpeg","keywords":["CIGARROS CONTRABANDO"],"articleSection":["Destaque 1","Pol\u00edcia"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/miradouronoticias.com\/site\/2022\/10\/19\/prf-apreende-50-mil-macos-de-cigarros-contrabandeados-dentro-de-caminhao-em-tres-marias-mg\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/miradouronoticias.com\/site\/2022\/10\/19\/prf-apreende-50-mil-macos-de-cigarros-contrabandeados-dentro-de-caminhao-em-tres-marias-mg\/","url":"https:\/\/miradouronoticias.com\/site\/2022\/10\/19\/prf-apreende-50-mil-macos-de-cigarros-contrabandeados-dentro-de-caminhao-em-tres-marias-mg\/","name":"PRF apreende 50 mil ma\u00e7os de cigarros contrabandeados dentro de caminh\u00e3o, em Tr\u00eas Marias (MG) - Miradouro Not\u00edcias","isPartOf":{"@id":"https:\/\/miradouronoticias.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/miradouronoticias.com\/site\/2022\/10\/19\/prf-apreende-50-mil-macos-de-cigarros-contrabandeados-dentro-de-caminhao-em-tres-marias-mg\/#primaryimage"},"image":{"@id":"https:\/\/miradouronoticias.com\/site\/2022\/10\/19\/prf-apreende-50-mil-macos-de-cigarros-contrabandeados-dentro-de-caminhao-em-tres-marias-mg\/#primaryimage"},"thumbnailUrl":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2022\/10\/29db2a9d-3961-4352-823a-ac1c47e99972.jpeg","datePublished":"2022-10-19T21:07:58+00:00","breadcrumb":{"@id":"https:\/\/miradouronoticias.com\/site\/2022\/10\/19\/prf-apreende-50-mil-macos-de-cigarros-contrabandeados-dentro-de-caminhao-em-tres-marias-mg\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/miradouronoticias.com\/site\/2022\/10\/19\/prf-apreende-50-mil-macos-de-cigarros-contrabandeados-dentro-de-caminhao-em-tres-marias-mg\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/miradouronoticias.com\/site\/2022\/10\/19\/prf-apreende-50-mil-macos-de-cigarros-contrabandeados-dentro-de-caminhao-em-tres-marias-mg\/#primaryimage","url":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2022\/10\/29db2a9d-3961-4352-823a-ac1c47e99972.jpeg","contentUrl":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2022\/10\/29db2a9d-3961-4352-823a-ac1c47e99972.jpeg","width":768,"height":576},{"@type":"BreadcrumbList","@id":"https:\/\/miradouronoticias.com\/site\/2022\/10\/19\/prf-apreende-50-mil-macos-de-cigarros-contrabandeados-dentro-de-caminhao-em-tres-marias-mg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/miradouronoticias.com\/site\/"},{"@type":"ListItem","position":2,"name":"PRF apreende 50 mil ma\u00e7os de cigarros contrabandeados dentro de caminh\u00e3o, em Tr\u00eas Marias (MG)"}]},{"@type":"WebSite","@id":"https:\/\/miradouronoticias.com\/site\/#website","url":"https:\/\/miradouronoticias.com\/site\/","name":"Miradouro Not\u00edcias","description":"Informa\u00e7\u00f5es da cidade e regi\u00e3o","publisher":{"@id":"https:\/\/miradouronoticias.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/miradouronoticias.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/miradouronoticias.com\/site\/#organization","name":"Miradouro Not\u00edcias","url":"https:\/\/miradouronoticias.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/miradouronoticias.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2022\/01\/logomarcamiradouronoticias.png","contentUrl":"https:\/\/miradouronoticias.com\/site\/wp-content\/uploads\/2022\/01\/logomarcamiradouronoticias.png","width":747,"height":263,"caption":"Miradouro Not\u00edcias"},"image":{"@id":"https:\/\/miradouronoticias.com\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/miradouronoticias.com\/site\/#\/schema\/person\/73440d8c82222950df86f3e1a16aad3b","name":"Cl\u00e1udia Olyver","sameAs":["http:\/\/www.miradouronoticias.com"],"url":"https:\/\/miradouronoticias.com\/site\/author\/claudia\/"}]}},"_links":{"self":[{"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/posts\/10182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/comments?post=10182"}],"version-history":[{"count":1,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/posts\/10182\/revisions"}],"predecessor-version":[{"id":10185,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/posts\/10182\/revisions\/10185"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/media\/10184"}],"wp:attachment":[{"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/media?parent=10182"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/categories?post=10182"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/miradouronoticias.com\/site\/wp-json\/wp\/v2\/tags?post=10182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}